{"id":2353,"date":"2018-02-08T10:53:17","date_gmt":"2018-02-08T09:53:17","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=2353"},"modified":"2018-02-08T10:53:18","modified_gmt":"2018-02-08T09:53:18","slug":"avis-pecetto-un-2017-incorniciare","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/02\/08\/avis-pecetto-un-2017-incorniciare\/","title":{"rendered":"Avis Pecetto: un 2017 da incorniciare"},"content":{"rendered":"<p>PECETTO &#8211; In occasione delle consueta assemblea annuale l\u2019Avis Pecetto mostra grande soddisfazione per il lavoro svolto nel corso del 2017. Il presidente Pier Luigi Arato spiega infatti che: \u201cgrazie all\u2019attivit\u00e0 svolta dall\u2019intero direttivo nell\u2019ambito della comunicazione e della sensibilizzazione a tutta la popolazione di Pecetto e dintorni, i risultati ottenuti nell\u2019anno trascorso sono incoraggianti, grazie soprattutto al buon incremento dei nuovi donatori e delle relative donazioni di sangue\u201d. I dati nel dettaglio verranno resi noti nel corso della gi\u00e0 citata assemblea, fissata per domenica 18 febbraio, alle 11.20, presso la sede associativa di piazza Rimembranza 7, alla quale sono attesi tutti i donatori, gli ex e gli amici simpatizzanti e collaboratori.<\/p>\n<p>Maggiori dettagli nell\u2019edizione in edicola il 14 febbraio<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":2354,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/2353"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=2353"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/2353\/revisions"}],"predecessor-version":[{"id":2355,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/2353\/revisions\/2355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/2354"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=2353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=2353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=2353"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=2353"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=2353"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=2353"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=2353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}