{"id":23834,"date":"2019-10-16T17:56:03","date_gmt":"2019-10-16T15:56:03","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=23834"},"modified":"2025-05-23T11:34:51","modified_gmt":"2025-05-23T09:34:51","slug":"case-affitto-offresi","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2019\/10\/16\/case-affitto-offresi\/","title":{"rendered":"CASE AFFITTO OFFRESI"},"content":{"rendered":"<p><strong>Moncalieri <\/strong>Il Casato Immobili Revigliasco strada Maddalena affittiamo in villa appartamento signorile mansardato di circa 105 mq molto ben tenuto e comprensivo di box auto doppio. Contratto 4 anni+4 mensile canone Euro 790,00 mensili+spese condominiali e riscaldamento. Libero dal 15 aprile, non arredato. APE Classe C. Codice Mon009. www.ilcasatoimmobili.it. Tel. 011. 642563<\/p>\n<p><strong>Moncalieri <\/strong>Il Casato Immobili Borgo Navile via Goito affittiamo appartamento ampio e spazioso bilocale finemente ristrutturato nel 2025 di circa 62 mq parzialmente arredato. Primo Piano. Contratto 4 anni+4 con canone mensile di Euro 580,00 mensili+spese condominiali e riscaldamento. Climatizzazione autonoma canalizzata nuova. Libero subito. APE Classe E. Codice Mon011. www.ilcasatoimmobili.it. Tel. 011. 642563<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":57009,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/23834"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=23834"}],"version-history":[{"count":3,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/23834\/revisions"}],"predecessor-version":[{"id":74322,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/23834\/revisions\/74322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/57009"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=23834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=23834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=23834"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=23834"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=23834"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=23834"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=23834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}