{"id":3498,"date":"2018-03-07T18:42:17","date_gmt":"2018-03-07T17:42:17","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=3498"},"modified":"2018-03-07T18:42:18","modified_gmt":"2018-03-07T17:42:18","slug":"les-folies-retro-domenica-pecetto","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/03\/07\/les-folies-retro-domenica-pecetto\/","title":{"rendered":"Les Folies R\u00e9tro domenica a Pecetto"},"content":{"rendered":"<p>PECETTO &#8211; Domenica 11 marzo, alle 17.30 nella bella cornice della chiesa sconsacrata dei Bat\u00f9 di piazza Roma, nell\u2019ambito della stagione musicale pecettese che si avvale della direzione artistica di Raffaele Tavano sar\u00e0 possibile ascoltare \u00abLes Folies R\u00e9tro\u00bb, un gruppo che si avvale delle voci di Francesca Mungiov\u00ec e Linda Lazzarotto e di Paolo Valente al pianoforte. Insieme metteranno in scema uno spettacolo fresco, attuale e travolgente:\u00a0 due giovani ragazze si raccontano al pubblico, in un dialogo sincero, dove vengono messi a nudo sentimenti ed emozioni.\u00a0 Un tavolo, del buon caff\u00e8, un pianoforte e un\u2019amicizia che supera le diversit\u00e0 e che fa da collante all\u2019intero spettacolo.\u00a0 Il tutto addolcito dalle swinganti note di grandi evergreen, dagli anni \u201840 ai giorni nostri, arrangiati dal maestro Paolo Valente e cantati appunto dalle voci di Les Folies R\u00e9tro, un duo che nasce nel 2016\u00a0 e finalizzato a rendere omaggio alle pi\u00f9 belle canzoni di tutti i tempi.\u00a0E nel ruolo di valore aggiunto nel 2018 si \u00e8 unito alla brigata Paolo Valente, appunto in qualit\u00e0 di pianista e arrangiatore.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":3499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/3498"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=3498"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/3498\/revisions"}],"predecessor-version":[{"id":3500,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/3498\/revisions\/3500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/3499"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=3498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=3498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=3498"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=3498"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=3498"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=3498"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=3498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}