{"id":41879,"date":"2021-07-22T10:39:33","date_gmt":"2021-07-22T08:39:33","guid":{"rendered":"https:\/\/euwps02.newsmemory.com\/ilmercoledi\/news\/?p=41879"},"modified":"2021-07-22T10:42:28","modified_gmt":"2021-07-22T08:42:28","slug":"rally-gli-italiani-in-scalata-al-roma-capitale","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2021\/07\/22\/rally-gli-italiani-in-scalata-al-roma-capitale\/","title":{"rendered":"RALLY &#8211; Gli italiani in scalata al Roma Capitale"},"content":{"rendered":"<p>Arriva una nuova chance per gli italiani di scalare la vetta d\u2019Europa. A poco pi\u00f9 di dieci giorni di distanza dai successi calcistici, il tricolore \u00e8 pronto a sventolare ancora in alto nella massima competizione continentale. Stavolta in casa, nel cuore d\u2019Italia, il pallone si fa da parte per lasciare spazio ai motori ed ai traversi del\u00a0<strong>Rally di Roma Capitale<\/strong>, in programma nel prossimo weekend dal 23 al 25 luglio. La nona edizione della gara organizzata da\u00a0<strong>Motorsport Italia<\/strong>\u00a0\u00e8 pronta a lanciare la doppia sfida per il\u00a0<strong>Campionato Italiano Rally Sparco<\/strong>\u00a0ed il\u00a0<strong>FIA European Rally Championship<\/strong>.<\/p>\n<p>Ormai un appuntamento fisso, quello di Roma, tra la massima serie nazionale giunta alla sua quinta gara e quella europea, per il terzo round stagionale, che anche quest\u2019anno porter\u00e0 lo spettacolo del rally dal centro della Citt\u00e0 Eterna fino agli asfalti attorno a Fiuggi. Alle due validit\u00e0 maggiori si aggiunge la nuova formula del\u00a0<strong>Rally di Roma Capitale Cup<\/strong>, che riunisce nella stessa competizione gli equipaggi in corsa per i trofei monomarca, tra i quali la debuttante Toyota Yaris GR Cup. Un incontro che ha chiamato a raccolta la bellezza di\u00a0<strong>119 vetture<\/strong>, tra le quali spiccano le\u00a0<strong>44 della classe maggiore R5<\/strong>, pronte a competere su\u00a0<strong>731,04 chilometri di percorso complessivo<\/strong>\u00a0dei quali\u00a0<strong>190,09 divisi su 13 prove speciali<\/strong>.<\/p>\n<p>PROGRAMMA IN BREVE | Il tutto sar\u00e0 visibile da start a stop grazie all\u2019imponente copertura mediatica orchestrata da ACI Sport ed Eurosport. L\u2019emittente della Federazione, sempre visibile sul canale 228 della piattaforma Sky, su\u00a0www.acisport.it\u00a0e su Facebook @ACISportTV, proporr\u00e0 un programma intenso a partire proprio dalla serata d\u2019apertura del venerd\u00ec, con la cerimonia iniziale a Castel Sant\u2019Angelo seguita dalla\u00a0<strong>nuova e suggestiva Power Stage attorno alle Terme di Caracalla<\/strong>\u00a0a partire dalle ore 20, visibile anche su RAI Sport, con le bellezze della Capitale a fare da sfondo al rally. Trasmissioni in diretta che proseguiranno anche per le due intense giornate di sabato e domenica, con collegamenti costanti dalle prove speciali e dalle zone nevralgiche dell\u2019evento. Per ciascuna delle due giornate sono previsti tre diversi tratti da affrontare due volte. Al sabato la prova speciale \u201cRocca di Cave\u201d (7,25 km) [ore 9.53 e 14.26], seguita dalla lunga \u201cRocca Santo Stefano\u201d (19,70 km) [ore 10.10 e 14.33] a chiudere il loop la \u201cAffile-Bellegra\u201d in due diverse versioni (da 7,34 km al primo giro e da 2,94km al secondo) [ore 11.05 e 16.35]. Domenica sar\u00e0 la giornata pi\u00f9 lunga ed intensa, che inizier\u00e0 e finir\u00e0 con la \u201cFiuggi-Guarcino\u201d (19,87 km) [ore 7.45, 13.09 e 17.15] unica prova da ripetere tre volte. In mezzo la speciale \u201cCollepardo\u201d (10,62km) [ore 8.36 e 14.00] quindi la pi\u00f9 lunga del rally \u201cSantopadre-Arpino\u201d (21,17km) [ore 9.43 e 15.13].<\/p>\n<p>IL MEGLIO D\u2019EUROPA | Una flotta di oltre cento auto in mano ai migliori piloti delle due serie, cos\u00ec il Rally di Roma Capitale annuncia un altro show. Le ultime edizioni hanno sempre offerto duelli avvincenti, spesso risolti nel finale, con gli italiani a tenere testa ai big dell\u2019ERC. Scenario che sembra destinato a ripetersi dato che non mancheranno i migliori stranieri come il plurititolato russo\u00a0<strong>Alexey Lukyanuk<\/strong>, due volte vincitore nel \u201918 e nel \u201920, attuale leader dell\u2019Europeo, su Citroen C3 R5. Oppure il norvegese\u00a0<strong>Andreas Mikkelsen<\/strong>\u00a0su Skoda Fabia R5, proveniente dal Mondiale come l\u2019altro russo\u00a0<strong>Nikolay Gryazin<\/strong>\u00a0su Volkswagen Polo R5. Sono solo alcuni dei grandi nomi internazionali di un rally che vedr\u00e0 24 nazionalit\u00e0 rappresentate. Gli stranieri saranno trasparenti ai fini del risultato del Campionato Italiano Rally Sparco, tutti ad eccezione dell\u2019irlandese\u00a0<strong>Craig Breen<\/strong>, l\u2019anello di congiunzione tra le due serie. Il pilota di Hyundai Motorsport navigato da Paul Nagle correr\u00e0 per entrambi i campionati con la sua i20 R5.<\/p>\n<p>Occhio per\u00f2 agli italiani, che si giocheranno una fetta importante del CIR Sparco in un round a coefficiente 1,5. A partire dal nuovo leader del tricolore\u00a0<strong>Fabio Andolfi<\/strong>. Il savonese, con alle note Stefano Savoia su Fabia R5, potr\u00e0 provare a sfruttare la gara di casa per Motorsport Italia per conquistare la sua prima vittoria assoluta stagionale. Ha perso la vetta della classifica invece\u00a0<strong>Giandomenico Basso<\/strong>\u00a0che, insieme a Lorenzo Granai sulla R5 ceca, vuole tornare al successo dove c\u2019era gi\u00e0 riuscito nel 2019 e dove ha conquistato 5 podi su 6 presenze. Deve invece riscattare una stagione fin qui bersagliata dalla sfortuna il campione in carica\u00a0<strong>Andrea Crugnola<\/strong>. Il varesino prover\u00e0 di nuovo a ripartire dopo due ritiri consecutivi, sempre con Pietro Ometto al fianco sulla Hyundai i20 R5, nella gara che lo scorso anno lo vide subito out ai primi crono e poi dominatore nella seconda fase.<\/p>\n<p>Intanto stanno facendo passi avanti importanti, soprattutto su asfalto, gli altri piloti di\u00a0<strong>ACI Team Italia<\/strong>\u00a0spesso tra i top del tricolore. Come il toscano\u00a0<strong>Tommaso Ciuffi<\/strong>, di rientro dopo l\u2019assenza sulla terra sammarinese, che in coppia con Nicol\u00f2 Gonella su Polo R5 continua a coltivare aspirazioni di vertice nel CIR Asfalto. Il ritiro non ha comunque cancellato la prestazione, l\u2019ennesima, di spessore per\u00a0<strong>Damiano De Tommaso<\/strong>\u00a0che ritrova alla destra Giorgia Ascalone e vorr\u00e0 tornare a punti con la C3 R5. Risultato ottimo nell\u2019ultima sulle strade bianche per l\u2019altro pilota di Motorsport Italia il piacentino\u00a0<strong>Andrea Mazzocchi<\/strong>, sempre su Fabia R5 con Silvia Gallotti, che stavolta dovr\u00e0 vedersela anche con tutti gli specialisti dell\u2019Asfalto. Tra questi il pavese\u00a0<strong>Giacomo Scattolon<\/strong>\u00a0rientrante in corsa con Giovanni Bernacchini su Polo R5.<\/p>\n<p>Sono tanti i piloti del CIRA che tornano in corsa in questo nuovo appuntamento tricolore. Molti in gran forma come il trevigiano\u00a0<strong>Marco Signor<\/strong>, di ritorno dal successo nella gara test in casa al Rally della Marca, per la prima volta in questo campionato affiancato da Patrick Bernardi sulla Volkswagen Polo R5. Gli altri saranno tutti armati di Skoda Fabia R5, come i ragazzi palermitani di ACI Team Italia\u00a0<strong>Marco Pollara<\/strong>, in arrivo dal successo in Coppa Rally di Zona al Rally dei Nebrodi con Daniele Mangiarotti e\u00a0<strong>Alessio Profeta<\/strong>, con Sergio Raccuia; quindi a completare il gruppo il reggiano\u00a0<strong>Antonio Rusce<\/strong>\u00a0con Sauro Farnocchia, il pilota di Sora\u00a0<strong>Liberato Sulpizio<\/strong>\u00a0sulle strade amiche, a pochi chilometri da casa, navigato da Alessio Angeli e la coppia di regine al Femminile nel tricolore formata da\u00a0<strong>Patrizia Perosino<\/strong>\u00a0al volante e Veronica Verzoletto alle note.<\/p>\n<p>Spiccano anche diverse presenze italiane tra i piloti in pianta stabile nell\u2019Europeo, tutti gi\u00e0 apprezzati quest\u2019anno nel Campionato Italiano Rally Terra, che correranno da outsider per il CIR Sparco ma come da regolamento potranno \u201ctogliere punti\u201d ai concorrenti del tricolore. Conoscono gi\u00e0 bene il Rally di Roma il veronese\u00a0<strong>Umberto Scandola,\u00a0<\/strong>stavolta insieme a Danilo Fappani su Hyundai i20 R5, perch\u00e9 lo ha vinto due volte e il cesenate\u00a0<strong>Simone Campedelli,<\/strong>\u00a0affiancato da Tania Canton su Polo R5, che conta sei presenze nella Capitale. Meno esperienza ma tanto talento per il giovane vicentino di\u00a0<strong>ACI Team Italia<\/strong>\u00a0<strong>Alberto Battistolli<\/strong>\u00a0in coppia con Simone Scattolin su Skoda Fabia R5, anche lui presente e apparso in forma lo scorso weekend sull\u2019asfalto del Rally della Marca.<\/p>\n<p>FASE CALDA PER IL CIR JUNIOR | Anche le strade del\u00a0<strong>Campionato Italiano Rally Junior<\/strong>\u00a0portano a Roma. Sar\u00e0 un passaggio importante per gli\u00a0<strong>11 ragazzi di ACI Team Italia<\/strong>\u00a0che si giocheranno la quarta delle sei gare in calendario. Sar\u00e0 il primo appuntamento dello Junior ad offrire un coefficiente 1,5 e aprir\u00e0 la volata verso gli ultimi due al Rally 1000 Miglia prima della Liburna Terra, ultimo e di nuovo a punteggio maggiorato. La Capitale rappresenta quindi un crocevia fondamentale, una chance in pi\u00f9 anche per gli Under 27 di sfruttare il fattore campo con la gestione tecnica del team di casa Motorsport Italia. Parte stavolta da leader l\u2019astigiano\u00a0<strong>Emanuele Rosso<\/strong>\u00a0con Andrea Ferrari alle note, forte di un vantaggio di 11 punti in classifica su\u00a0<strong>Giorgio Cogni<\/strong>\u00a0con Gabriele Zanni e\u00a0<strong>Mattia Vita<\/strong>\u00a0con Max Bosi, equipaggi appaiati in seconda posizione generale. Nono sono distanti anche gli altri, con altri cinque piloti tutti appaiati in una manciata di punti. Sta ottenendo risultati e si \u00e8 confermato costante l\u2019aostano\u00a0<strong>Marcel Porliod<\/strong>\u00a0insieme ad Andr\u00e9 Perrin, mentre sta crescendo alla distanza il rendimento di\u00a0<strong>Roberto Dapr\u00e0<\/strong>, stavolta con la novit\u00e0 di Chiara Lombardi alle note, vincitore dell\u2019ultimo round sulla terra di San Marino. Seguono nell\u2019ordine di tre punti il varesino\u00a0<strong>Riccardo Pederzani<\/strong>\u00a0con Daniel Pozzi, il salentino\u00a0<strong>Guglielmo De Nuzzo<\/strong>\u00a0con Andrea Colapietro e il messinese\u00a0<strong>Alessandro Casella<\/strong>, con Rosario Siragusano, vincitore a Sanremo e da l\u00ec in poi spesso limitato dalla sfortuna. La stessa che ha costretto al ritiro nell\u2019ultima gara il torinese\u00a0<strong>Davide Porta<\/strong>\u00a0e Andrea Segir, mentre migliora un passo alla volta l\u2019esperienza del triestino\u00a0<strong>Francesco Lovati<\/strong>\u00a0con Giacomo Ciucci e del savonese\u00a0<strong>Andrea Piccardo<\/strong>, con Luca Migone, anche lui ritirato sulle strade bianche de piccolo stato.<\/p>\n<p>CIR DUE RUOTE MOTRICI | Oltre ai piloti del CIR Junior ci saranno anche tutti i top in lizza per il tricolore Due Ruote Motrici. Presenti i fratelli messinesi\u00a0<strong>Andrea e Giuseppe Nucita<\/strong>, sempre pi\u00f9 leader di categoria, in cerca della nuova affermazione sul palcoscenico di caratura internazionale con la loro Peugeot 208 Rally4 ufficiale. Non staranno a guardare gli altri, come i tanti giovani che stanno cercando di avvicinarsi al capofila. Ci \u00e8 riuscito all\u2019ultima e ci riprover\u00e0 a Roma il trentino\u00a0<strong>Fabio Farina<\/strong>, anche lui sulla francese R2 con Luca Gulgielmetti, quindi il lucchese\u00a0<strong>Christopher Lucchesi Jr.<\/strong>\u00a0che insieme a Titti Ghilardi torna sulla cresta dell\u2019onda da leader del CIR Asfalto Due Ruote Motrici, dopo un turno di assenza, con i colori di ACI Team Italia sulla livrea della sua 208. Stessa vettura anche per il vicentino\u00a0<strong>Nicola Cazzaro<\/strong>\u00a0con Giovanni Brunaporto e per il bresciano\u00a0<strong>Jacopo Trevisani<\/strong>\u00a0in tandem con Fabio Grimaldi. Sempre al volante di Ford Fiesta Rally 4 torna in gara anche il pistoiese\u00a0<strong>Daniele Campanaro<\/strong>\u00a0con Irene Porcu.<\/p>\n<p>ARRIVA LA GR YARIS RALLY CUP | Sar\u00e0 il weekend del debutto per la\u00a0<strong>GR Yaris Rally Cup<\/strong>. Il nuovo trofeo monomarca firmato dalla casa giapponese e organizzato da Toyota Motor Italia, porter\u00e0 alla ribalta\u00a0<strong>11 scattanti vetture di classe R1T 4\u00d74 Nazionale<\/strong>\u00a0nel primo dei cinque round fissati in calendario. Da Roma, al 1000 Miglia, al Rally Due Valli insieme al CIR Sparco, quindi la sfida al fianco della Finale Nazionale ACI Sport Rally Cup Italia nel Rally Citt\u00e0 di Modena e l\u2019ultima al Rally di Monza. Un percorso che garantisce adrenalina e promette spettacolo come gli equipaggi che hanno aderito alla nuova serie. Alcuni volti noti come il parmense Simone Rivia, gi\u00e0 protagonista in R1 nei campionati italiani, il bresciano Ilario Bondioni visto all\u2019opera anche sulle R5 e tra le R2 nel CIRA, alcuni d\u2019esperienza come il valtellinese Marco Gianesini, altri esordienti come Angelo Grossi, figlio del \u201cPucci\u201d leggenda dei rally sterrati all\u2019italiana. Una prima uscita da tenere d\u2019occhio che si svolger\u00e0 all\u2019interno del Rally di Roma Capitale Cup, che effettuer\u00e0 lo stesso percorso della gara maggiore.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":41878,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/41879"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=41879"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/41879\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/41878"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=41879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=41879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=41879"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=41879"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=41879"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=41879"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=41879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}