{"id":41995,"date":"2021-07-27T18:54:49","date_gmt":"2021-07-27T16:54:49","guid":{"rendered":"https:\/\/euwps02.newsmemory.com\/ilmercoledi\/news\/?p=41995"},"modified":"2021-07-27T18:57:15","modified_gmt":"2021-07-27T16:57:15","slug":"adriano-beschin-domina-la-michelin-historic-rally-cup-2021-al-vallate-aretine","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2021\/07\/27\/adriano-beschin-domina-la-michelin-historic-rally-cup-2021-al-vallate-aretine\/","title":{"rendered":"Adriano Beschin domina la Michelin Historic Rally Cup 2021 al Vallate Aretine"},"content":{"rendered":"<p>L\u2019undicesima edizione del\u00a0<b><i>Historic Rally Vallate Aretine<\/i><\/b>, se proprio non passer\u00e0 alla storia, verr\u00e0 almeno ricordato per un pezzo a causa dell\u2019elevato tasso di ritiri che hanno condizionato la corsa. Sar\u00e0 per il fatto che per quest\u2019anno la gara maremmana si \u00e8 spostata nella\u00a0<b>canicola<\/b>\u00a0di fine luglio che, si sa, non favorisce la serenit\u00e0 di piloti e la salubrit\u00e0 dei motori, ma dei 51 equipaggi regolarmente al via 22 si sono fermati anzi tempo. Oltre il 40%. E non \u00e8 andata meglio ai protagonisti della\u00a0<b>Michelin Historic Rally Cup<\/b>\u00a0partiti in 15 e arrivati appena in otto. Quasi il 50%.\u00a0\u00a0Se a tutti questi aggiungiamo anche lo stop dell\u2019<b>Ambasciatore Michelin<\/b>\u00a0nel Quarto Raggruppamento,\u00a0<b>Matteo Luise<\/b>, fermato da una piccola ma dannosa uscita di strada nel corso della\u00a0<b>Rassinata<\/b>\u00a0mattutina, dove il rovigotto ha rovinato una sospensione dopo aver messo le ruote anteriori nello sporco, \u00e8 facile comprendere quanto sia stata impegnativa e selettiva la gara aretina.<\/p>\n<p>Chi non ha avuto il bench\u00e9 minimo problema \u00e8 stato il veneto\u00a0<b>Adriano Beschin<\/b>, affiancato sulla sua\u00a0<b>Porsche 911 SC<\/b>\u00a0da Federico\u00a0<b>Migliorini<\/b>, che ha condotto non solo la classifica del Challenge della Casa di Clermont Ferrand, concedendo agli avversari una sola delle otto prove speciali, ma imponendosi con autorevolezza e assoluto dominio anche nel\u00a0<b>Terzo Raggruppamento<\/b>\u00a0della gara e nella relativa classe, oltre a salire sul palco di arrivo in nona posizione assoluta. \u201c<i>Ho usato gli stessi\u00a0<b>pneumatici Michelin<\/b>\u00a0che avevo usato al Campagnolo e si sono comportati benissimo non dandomi la minima preoccupazione dal primo all\u2019ultimo metro a dimostrazione di quanto siano non solo performanti e non hanno decadimento prestazionale durante la gara<\/i>\u201d. Alle spalle di Beschin funamboleggia\u00a0<b>Luciano Chivelli<\/b>, come sempre affiancato dalla figlia\u00a0<b>Lorena<\/b>, che chiude in undicesima posizione assoluta, ed anche per lui c\u2019\u00e8 la soddisfazione di aver vinto la Classe e il Terzo Raggruppamento di Gruppo 2 con la piccola\u00a0<b>Fiat 127<\/b>. Oltre a essere stato l\u2019unico a mettere in una prova la sua 127 davanti alla Porsche di Beschin, fatto avvenuto nel passaggio mattutino sulla\u00a0<b>Portole. Chivelli<\/b>\u00a0aveva iniziato un gran bel duello a suon di tempi siderali con Luca Delle Coste, affiancato come sempre da Franca\u00a0<b>Regis Milano<\/b>\u00a0sulla\u00a0<b>Ritmo 75<\/b>, duello terminato proprio in dirittura di arrivo per la rottura del secondo semiasse da parte del pilota varesino. Terza piazza, con onore e costanza per i coniugi biellesi\u00a0<b>Luca Valle<\/b>\u00a0e Cristiana\u00a0<b>Bertoglio<\/b>, che hanno saputo mantenere un ritmo veloce e senza cedimenti per tutta la gara che li ha portati a chiudere in quattordicesima posizione assoluta del rally conquistando la palma dei pi\u00f9 veloci di Classe.<\/p>\n<p>Dopo quattro delle dieci gare in programma la classifica assoluta della\u00a0<b>Michelin Historic Rally Cup<\/b>\u00a0vede ancora al comando\u00a0<b>Giacomo Questi<\/b>, nonostante il ritiro aretino, ma compiono un deciso balzo in avanti\u00a0<b>Beschin<\/b>\u00a0che sale al terzo posto a 13 punti da Questi e\u00a0<b>Chivelli<\/b>, appena due punti dietro il veneto della Porsche, con a ruota i ritirati\u00a0<b>Luca Delle Coste<\/b>, sceso al quarto posto, che mantiene un punto di vantaggio su\u00a0<b>Luca Valle<\/b>, capace di raccogliere un bottino pesante al\u00a0<b>Vallate Aretine<\/b>.<\/p>\n<p>Successo secco e senza dubbi per\u00a0<b>Adriano Beschin<\/b>\u00a0e Luca Migliorini con la loro\u00a0<b>Porsche 911 SC<\/b>\u00a0nel\u00a0<b>Terzo Raggruppamento<\/b>\u00a0della\u00a0<b>Michelin Historic Rally Cup<\/b>\u00a0(e anche in generale nel rally). che precedono i velocissimi friulani\u00a0<b>Luciano<\/b>\u00a0e\u00a0<b>Lorena Chivelli<\/b>\u00a0con la\u00a0<b>Fiat 127<\/b>, protagonisti di un bel duello con\u00a0<b>Luca Delle Coste<\/b>\u00a0e Franca\u00a0<b>Regis Milano<\/b>, che hanno capito fin dall\u2019inizio che la trasferta aretina non sarebbe stata delle pi\u00f9 semplici per la loro\u00a0<b>Fiat Ritmo 75<\/b>. Gi\u00e0 nella prima prova del venerd\u00ec sera hanno rotto un semiasse,\u00a0<b>perdendo 52\u201d<\/b>\u00a0da Beschin, essendo costretti nelle speciali successive a lanciarsi all\u2019inseguimento per risalire dal settimo posto della\u00a0<b>Michelin Historic Rally Cup<\/b>, in cui erano precipitati dopo la prima prova, sino alla terza posizione nella quale si apprestavano ad affrontare la speciale finale. Ma la\u00a0<b>rottura<\/b>\u00a0di un secondo semiasse, questa volta il sinistro, faceva concludere loro la speciale con 2\u201942\u201d di ritardo, riuscendo a conservare la terza posizione in classifica. Non riuscivano per\u00f2 a\u00a0<b>completare il trasferimento<\/b>\u00a0finale, cedendo cosi la terza piazza sia assoluta sia di Terzo Raggruppamento di\u00a0<b>Michelin Historic Rally Cup<\/b>\u00a0ai regolari\u00a0<b>Luca Valle<\/b>\u00a0e Cristiana\u00a0<b>Bertoglio<\/b>, autori di una gara perfetta e senza sbavature con la loro\u00a0<b>Porsche 911 SC<\/b>.<\/p>\n<p>La quarta piazza sia di\u00a0<b>Terzo Raggruppamento<\/b>\u00a0sia assoluta della\u00a0<b>Michelin Historic Rally Cup<\/b>\u00a0va ai liguri\u00a0<b>Valtero Gandolfo<\/b>\u00a0e Marino\u00a0<b>Mondino<\/b>, che per\u00f2 non sono mai riusciti a far funzionare al meglio il motore della\u00a0<b>Fiat 127,\u00a0<\/b>problema che non ha permesso loro di andare a duellare con\u00a0<b>Chivelli<\/b>, come sarebbe stato nelle loro intenzioni. Dietro\u00a0<b>Gandolfo<\/b>\u00a0si classificano i tedeschi\u00a0<b>Peter\u00a0<\/b>ed\u00a0<b>Elke Goekel<\/b>\u00a0con la loro\u00a0<b>Opel Kadett D<\/b>\u00a0che oltre ad apprezzare sempre pi\u00f9 le prove speciali italiane, sono arrivati a una buona conoscenza della nostra lingua. A chiudere la striscia di\u00a0<b>Terzo Raggruppamento<\/b>\u00a0della\u00a0<b>Michelin Historic Rally Cup<\/b>\u00a0ci pensano i toscani\u00a0<b>Giovanni Lorenzi<\/b>-Simone\u00a0<b>Canigiani<\/b>\u00a0con la loro\u00a0<b>Fiat 127 Sport<\/b>, autori di una gara senza problemi. Oltre a\u00a0<b>Luca Delle Coste<\/b>, ritiro anche per il leader della Coppa,\u00a0<b>Giacomo Questi<\/b>, con Giovanni\u00a0<b>Morina<\/b>\u00a0sul sedile di destra, che scoppia il motore della sua\u00a0<b>Opel Ascona SR<\/b>\u00a0fin dalla prima prova del sabato sera. Unica consolazione per il portacolori del\u00a0<b>Team Bassano<\/b>\u00a0l\u2019aver mantenuto il comando della Coppa Michelin storica, e del Terzo Raggruppamento con buon margine su\u00a0<b>Beschin, Chivelli<\/b>\u00a0e\u00a0<b>Delle Coste.<\/b><\/p>\n<p>Il\u00a0<b>Secondo Raggruppamento<\/b>\u00a0della\u00a0<b>Michelin Historic Rally Cup<\/b>\u00a0vede quattro dei cinque partecipanti fermarsi strada facendo, con l\u2019eccezione del solo\u00a0<b>Luigi Annoni<\/b>, affiancato da Giampaolo\u00a0<b>Mantovani<\/b>, su\u00a0<b>Fiat 128 Coup\u00e9<\/b>, che conquista la quinta piazza assoluta fra i trofeisti Michelin, oltre la 21esima posizione assoluta e la vittoria di classe in gara. Il primo a lasciare la pattuglia dei concorrenti \u00e8 stato il biellese\u00a0<b>Luca Prima Mello<\/b>, che abbandona la sua\u00a0<b>BMW 2002 Ti<\/b>\u00a0e il navigatore Luca\u00a0<b>Pieri<\/b>\u00a0ancor prima di partire per precipitarsi a casa ad abbracciare la moglie che ha appena dato alla luce una bambina. Auguri. Meno felice il ritiro di\u00a0<b>Bruno Graglia<\/b>\u00a0e Roberto\u00a0<b>Barbero<\/b>\u00a0che rompono una sospensione della loro\u00a0<b>Fiat Abarth 124 Rally<\/b>\u00a0in un punto particolarmente lento della seconda prova speciale parcheggiando cos\u00ec a bordo strada la loro vettura senza ulteriori danni. La terza prova, prima di sabato mattina, \u00e8 fatale al britannico\u00a0<b>Trevor Smithson<\/b>\u00a0con problemi di alimentazione alla sua\u00a0<b>Alpine A110<\/b>\u00a0che divide con Alessio\u00a0<b>Chiantelli<\/b>. Mentre \u00e8 arrivato sino alla penultima prova\u00a0<b>Marco Guerreti<\/b>, con Andrea\u00a0<b>Dal Maso<\/b>, prima che si bloccasse il cambio della sua\u00a0<b>Fiat 128 Coup\u00e9<\/b>\u00a0con la quale era all\u2019inseguimento della vettura gemella di\u00a0<b>Annoni<\/b>. Dopo il\u00a0<b>Vallate Aretine<\/b>\u00a0il\u00a0<b>Secondo Raggruppamento<\/b>\u00a0vede sempre al comando\u00a0<b>Luca Prina Mello<\/b>, con\u00a0<b>Luigi Annoni<\/b>\u00a0che sale al secondo posto a fianco dell\u2019assente\u00a0<b>Ermanno Caporale<\/b>\u00a0davanti a\u00a0<b>Bruno Graglia<\/b>\u00a0che esce dalla zona podio.<\/p>\n<p>Si prospettava un gran duello nel\u00a0<b>Primo Raggruppamento<\/b>\u00a0della\u00a0<b>Michelin Historic Rally Cup<\/b>\u00a0fra la\u00a0<b>Porsche 911S<\/b>\u00a0di\u00a0<b>Cesare Bianco<\/b>-Stefano\u00a0<b>Casazza<\/b>\u00a0e\u00a0<b>Lancia Fulvia HF 1.3<\/b>\u00a0di\u00a0<b>Massimo Giuliani<\/b>\u00a0e Claudia\u00a0<b>Sora<\/b>. E in effetti cos\u00ec \u00e8 stato per le prime tre speciali, con\u00a0<b>Bianco<\/b>\u00a0che si impone nella prima prova per soli 1\u201d6 su\u00a0<b>Giuliani<\/b>, che ribalta il risultato a suo favore sulla ripetizione notturna di\u00a0<b>Parco di Lignano<\/b>\u00a0andando al riposo con 7\u201d di vantaggio sul pilota piemontese, per poi contenere il ritardo sulla\u00a0<b>Portole<\/b>\u00a0mattutina. Prima per\u00f2 di entrare nella successiva\u00a0<b>Rassinata<\/b>\u00a0si rompe il filo dell\u2019acceleratore della\u00a0<b>Fulvia<\/b>\u00a0costringendo il portacolori di\u00a0<b>Rally Club Team<\/b>\u00a0ad alzare bandiera bianca, mentre il pilota della\u00a0<b>Porsche<\/b>\u00a0prosegue indisturbato, nonostante il sei cilindri di Stoccarda non dia il meglio di s\u00e9, andando a vincere il Gruppo anche della gara. Con questo risultato\u00a0<b>Bianco<\/b>\u00a0allunga decisamente nella classifica di\u00a0<b>Primo Raggruppamento<\/b>\u00a0con buon margine su\u00a0<b>Giuliani<\/b>.<\/p>\n<p>Anche le classifiche di classe della\u00a0<b>Michelin Historic Rally Cup<\/b>\u00a0cominciano ad assumere una precisa fisionomia. In\u00a0<b>Classe M1 Chivelli<\/b>\u00a0porta a dodici punti il suo vantaggio su\u00a0<b>Gandolfo<\/b>, mentre in\u00a0<b>M2 Delle Coste<\/b>\u00a0mantiene un lieve margine sull\u2019assente\u00a0<b>Massimo Giudicelli<\/b>. Fermi anzi tempo i due leader,\u00a0<b>Questi<\/b>\u00a0e\u00a0<b>Prina<\/b>\u00a0Mello cambia poco la classifica della\u00a0<b>Classe M3<\/b>\u00a0con\u00a0<b>Cesare Bianco<\/b>\u00a0che supera\u00a0<b>Bruno Graglia<\/b>\u00a0e sale sul podio della graduatoria. Infine la costanza di risultati di\u00a0<b>Luca Valle<\/b>\u00a0lo mantiene al comando della\u00a0<b>Classe M4<\/b>\u00a0anche se viene decisamente avvicinato da\u00a0<b>Adriano Beschin<\/b>.<\/p>\n<p>Prossimo appuntamento con la\u00a0<b>Michelin Historic Rally Cup<\/b>\u00a0a Udine il 20-21 agosto per il\u00a0<b>25\u00b0 Rally Alpi Orientali Historic.<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":41994,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[395,10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/41995"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=41995"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/41995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/41994"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=41995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=41995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=41995"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=41995"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=41995"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=41995"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=41995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}