{"id":42567,"date":"2021-08-25T17:18:15","date_gmt":"2021-08-25T15:18:15","guid":{"rendered":"https:\/\/euwps02.newsmemory.com\/ilmercoledi\/news\/?p=42567"},"modified":"2021-08-25T17:18:40","modified_gmt":"2021-08-25T15:18:40","slug":"paralimpiadi-a-tokyo-carlotta-gilli-parte-con-loro-ed-il-record-nei-100-delfino","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2021\/08\/25\/paralimpiadi-a-tokyo-carlotta-gilli-parte-con-loro-ed-il-record-nei-100-delfino\/","title":{"rendered":"Paralimpiadi, a Tokyo Carlotta Gilli parte con l&#8217;oro ed il record nei 100 delfino"},"content":{"rendered":"<p>Con una prestazione praticamente perfetta la Carlotta Gilli ha portato la prima medaglia d&#8217;oro al medagliere paralimpico dell&#8217;Italia nella seconda parte dei Giochi di Tokyo apertasi ieri. La moncalierese, tesserata Rari Nantes Torino e Fiamme Oro, ha centrato il successo nei 100 farfalla (o delfino che dir si voglia) categoria S13 rimanendo a lungo con le mani oltre la linea virtuale del record del mondo che peraltro gi\u00e0 le apparteneva abbassandolo nuovamente a 1&#8217;02&#8243;65. Ad impreziosire la gara per i colori azzurri l&#8217;incredibile secondo posto di Alessia Berra con una gran rimonta nella seconda vasca.<\/p>\n<p><em>&#8220;Sono veramente senza parole<\/em> &#8211; ha commentato a caldo Carlotta &#8211;<em>. E&#8217; valsa la pena aspettare un anno in pi\u00f9. Questa gara l&#8217;ho sognata tantissime volte e me la immaginavo cos\u00ec. Volevo conquistare quel titolo che a Londra mi era sfuggito e sono arrivata qui con la voglia di riprendermi i 100 delfino. Ringrazio tantissimo anche Alessia che mi ha tranquillizzata. Con il primo e il secondo posto abbiamo fatto un capolavoro. Questa medaglia \u00e8 stata vinta nei mesi passati, grazie al supporto del mio allenatore, del mio staff, delle mie societ\u00e0 e della mia famiglia&#8221;<\/em>.<\/p>\n<p>In seguito seconda medaglia d&#8217;oro per l&#8217;Italia grazie al successo di Francesco Bocciardo nei 200 stile libero categoria S5 che si aggiunge al bronzo conquistato da\u00a0Francesco Bettella nei 100 metri dorso S1 con cui la nazionale azzurra aveva aperto il proprio medagliere.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":42566,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/42567"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=42567"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/42567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/42566"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=42567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=42567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=42567"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=42567"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=42567"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=42567"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=42567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}