{"id":43068,"date":"2021-09-23T18:24:42","date_gmt":"2021-09-23T16:24:42","guid":{"rendered":"https:\/\/euwps02.newsmemory.com\/ilmercoledi\/news\/?p=43068"},"modified":"2021-09-23T19:04:50","modified_gmt":"2021-09-23T17:04:50","slug":"eccellenza-girone-b-il-turno-infrasettimanale-regala-un-chisola-solo-al-comando","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2021\/09\/23\/eccellenza-girone-b-il-turno-infrasettimanale-regala-un-chisola-solo-al-comando\/","title":{"rendered":"Eccellenza girone B, il turno infrasettimanale regala un Chisola solo al comando"},"content":{"rendered":"<p>Primo tentativo di fuga nel girone B di Eccellenza. A regalarlo un Chisola che, partito malissimo in Coppa, in campionato si \u00e8 ritrovato ergendosi solitaria in vetta alla classifica dopo il primo dei due turni infrasettimanali. Da dire che i vinovesi erano partiti male anche con il Moretta mercoled\u00ec sera, tornando negli spogliatoi all&#8217;intervallo sotto 1-0 in virt\u00f9 della rete di Tonini a met\u00e0 frazione. Nella ripresa, tuttavia, ad esaltarsi \u00e8 stato il bomber Kamal Rizq che ha dapprima impattato il punteggio poi, ormai in vista del 90&#8242;, completato il sorpasso per il 2-1 conclusivo.<\/p>\n<p>Alle spalle dell&#8217;undici di mister Meloni un trio formato dal Cuneo 1905 Olmo, superato di misura in casa dal Rivoli a segno con Pinelli in avvio di ripresa; l&#8217;Alba Calcio, che si porta sul 3-0 in 47&#8242; con Rossi, Galasso e Cornero poi rischia l&#8217;aggancio da una Pro Dronero che risale sino al 3-2 grazie a De Peralta e Dutto; ed il Pinerolo, corsaro nel finale a Castellazzo Bormida grazie alla rete di Bosco.<\/p>\n<p>In fondo alla classifica rimane al palo l&#8217;Atletico Torino che dopo i quattro gol patiti proprio dal Chisola domenica ne incassa altri sei a Centallo. E rimangono ad un solo punto le citate Pro Dronero e Castellazzo Bormida ed il Benarzole superato di misura nella ripresa dal San Domenico savio Asti.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>CHISOLA CALCIO &#8211; MORETTA 2-1<\/strong> <em>(primo tempo 0-1)<\/em><\/p>\n<p><strong>Chisola Calcio:<\/strong> Marcaccini, Dagasso, Menon, Grancitelli, Bordone, Degrassi, Bottale (75&#8242; Perotti), Germinario, Rizq, Zeni (88&#8242; Rotondo), Ramondo (82&#8242; Geraci).\u00a0(12. Curreli, Bolla, Bernardon, Turatello, Viano, Guarnieri) <strong>All.:<\/strong> Marcello Meloni,<\/p>\n<p><strong>Moretta:<\/strong> Lerda, Leanza, Tonini (80&#8242; Capuano), Passero, Morello (88&#8242; Blencio), Faridi, Fioriello (73&#8242; Soldano), Sillah (59&#8242; Mazzi), Savino (64&#8242; Montante), Pizzolla, Aiello.\u00a0(12. Trocano, Previati, Giraudo) <strong>All.:<\/strong> Ettore Cellerino.<\/p>\n<p><strong>Terna:<\/strong> Cavallo di Cuneo assistito dai signori Mariut (Asti) e D&#8217;Acunzi (Alessandria).<\/p>\n<p><strong>Reti:<\/strong> 27&#8242; Tonini (M); 74&#8242; e 89&#8242; Rizq (C).<\/p>\n<p><strong>Note.<\/strong> <em>Ammoniti:<\/em> Degrassi, Perotti (C); Tonini, Fioriello, Savino e Pizzolla (M).<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ECCELLENZA Girone B<\/strong><\/p>\n<p><em><strong>Risultati 3a giornata:<\/strong><\/em> Acqui Fc &#8211; Albese 0-3; Alba Calcio &#8211; Pro Dronero 3-2; Castellazzo Bormida &#8211; Pinerolo 0-1; Cbs Scuola Calcio &#8211; Vanchiglia 1915 1-1; Chisola &#8211; Moretta 2-1; Cuneo 1905 Olmo &#8211; Rivoli 0-1; Giovanile Centallo &#8211; Atletico Torino 6-1; San Domenico Savio &#8211; Benarzole 1-0. Risposava: Lucento.<\/p>\n<p><strong><em>Classifica:<\/em><\/strong> Chisola <em><strong>7<\/strong><\/em>; Cuneo 1905 Olmo, Alba Calcio, Pinerolo <strong><em>6<\/em><\/strong>; Giovanile Centallo, Rivoli, Vanchiglia 1915 <em><strong>5<\/strong><\/em>; Albese, Moretta, Cbs Scuola Calcio, Acqui Fc <strong><em>4<\/em><\/strong>; Lucento*, San Domenico Savio Asti* <em><strong>3<\/strong><\/em>; Pro Dronero*, Benarzole, Castellazzo Bormida <strong><em>1<\/em><\/strong>; Atletico Torino <em><strong>0<\/strong><\/em>. (* riposo gi\u00e0 rispettato)<\/p>\n<p><em><strong>Prossimo turno<\/strong> (26\/09 h. 15):<\/em> Atletico Torino &#8211; Cuneo 1905 Olmo; Albese &#8211; Chisola; Benarzole &#8211; Lucento; Moretta &#8211; Giovanile Centallo; Pinerolo &#8211; Acqui Fc; Pro Dronero &#8211; Cbs Scuola Calcio; Rivoli &#8211; San Domenico Savio Asti; Vanchiglia 1915 &#8211; Castellazzo Bormida. <em>Riposer\u00e0:<\/em> Alba Calcio.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":43067,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/43068"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=43068"}],"version-history":[{"count":2,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/43068\/revisions"}],"predecessor-version":[{"id":43070,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/43068\/revisions\/43070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/43067"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=43068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=43068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=43068"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=43068"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=43068"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=43068"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=43068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}