{"id":4315,"date":"2018-03-29T08:50:17","date_gmt":"2018-03-29T06:50:17","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=4315"},"modified":"2018-03-29T08:50:18","modified_gmt":"2018-03-29T06:50:18","slug":"cambiano-venerdi-sera-via-crucis-lungo-le-strade-centrali","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/03\/29\/cambiano-venerdi-sera-via-crucis-lungo-le-strade-centrali\/","title":{"rendered":"Cambiano: venerd\u00ec sera Via Crucis lungo le strade centrali"},"content":{"rendered":"<p>CAMBIANO &#8211; Sar\u00e0 una vera e propria ricostruzione della tappe del calvario di Ges\u00f9 la Via Crucis in programma a Cambiano per la serata di domani, 30 marzo, Venerd\u00ec Santo. Un evento reso possibile dall\u2019impegno degli organizzatori della parrocchia Santi Vincenzo e Anastasio, ma soprattutto dalla disponibilit\u00e0 dei circa sessanta volontari che di fatto metteranno in scena la rappresentazione nel cuore del paese, con tanto di costumi per renderla ancora pi\u00f9 realistica. E il tutto si dipaner\u00e0 lungo le vie principali per circa un\u2019ora e mezza, rappresentando l\u2019ultimo appuntamento di preparazione all\u2019ormai imminente Pasqua.<\/p>\n<p>La partenza della processione \u00e8 fissata per le 21 dal sagrato della chiesa maggiore, dal quale il serpentone umano proseguir\u00e0 in direzione di piazzetta Burzio e della scuola materna Gribaudi. Da quel punto inforcher\u00e0 via San Francesco d\u2019Assisi per snodarsi verso l\u2019oratorio San Luigi di vicolo Colombaro e poi via Borgarelli. L\u2019arrivo avverr\u00e0 nella centralissima piazza Cavour, dove verr\u00e0 ricostruita la scena pi\u00f9 drammatica e al tempo stesso densa di emozioni: quella della crocifissione. Inoltre, a rendere ancora pi\u00f9 suggestiva la rappresentazione, provvederanno una serie di letture tratte dal Vangelo, che verranno sempre eseguite dalla compagnia di volontari che inscener\u00e0 il tutto.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":4316,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/4315"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=4315"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/4315\/revisions"}],"predecessor-version":[{"id":4317,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/4315\/revisions\/4317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/4316"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=4315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=4315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=4315"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=4315"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=4315"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=4315"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=4315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}