{"id":45054,"date":"2022-01-24T02:35:13","date_gmt":"2022-01-24T01:35:13","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=45054"},"modified":"2022-01-24T02:36:22","modified_gmt":"2022-01-24T01:36:22","slug":"tennis-torno-invernale-al-roma-20","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2022\/01\/24\/tennis-torno-invernale-al-roma-20\/","title":{"rendered":"TENNIS &#8211; Torno Invernale al \u00abRoma 20\u00bb"},"content":{"rendered":"<p align=\"JUSTIFY\">Al secondo Torneo Invernale \u00abRome to Rome\u00bb i protagonisti sono stati i forestieri. Il successo dell&#8217;evento organizzato dal club cambianese Roma 20 \u00e8 infatti andato all&#8217;atleta della Granda Vittorio Maurino, over 50 del DLF Cuneo. In finale infatti ha sconfitto per 6-3 il torinese del circolo Rosselli Alessandro Casale. Per i due finalisti per\u00f2 l&#8217;approdo al match conclusivo non \u00e8 stato una passeggiata. Nei quarti Maurino ha superato con grande fatica (6-5) il rivolese Riccardo Cinquemani del Tennis 2000, mentre in semifinale \u00e8 stato con un meno sofferto 6-3 che ha chiuso la questione con il torinese Andrea Borio, alfiere del De Coubertin. Casale invece ha passato i quarti con scioltezza (6-1 con Lorenzo Benanti del New Country Torino) ma ha patito tantissimo in semifinale: 6-5 con Fabio Barcello del gi\u00e0 citato Tennis 2000 di Rivoli, numero tre del tabellone e non per nulla rivelatosi un ostico rivale.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":17218,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/45054"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=45054"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/45054\/revisions"}],"predecessor-version":[{"id":45067,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/45054\/revisions\/45067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/17218"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=45054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=45054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=45054"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=45054"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=45054"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=45054"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=45054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}