{"id":45795,"date":"2022-03-04T18:13:59","date_gmt":"2022-03-04T17:13:59","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=45795"},"modified":"2022-03-04T18:15:16","modified_gmt":"2022-03-04T17:15:16","slug":"serie-d-girone-top-alberti-trascina-la-secursat-e-labc-incassa-il-primo-ko","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2022\/03\/04\/serie-d-girone-top-alberti-trascina-la-secursat-e-labc-incassa-il-primo-ko\/","title":{"rendered":"Serie D Girone Top, Alberti trascina la Secursat e l&#8217;Abc incassa il primo ko"},"content":{"rendered":"<p>Partita di categoria superiore per l&#8217;esordio nel girone Top di serie D di Abc Carmagnola e Secursat Scuola Basket Asti. E non poteva che essere altrimenti visto il cammino mostrato nella prima fase dai due quintetti anche se l&#8217;assenza di Mudadu nelle fila carmagnolesi ha tolto alla contesa un protagonista certo mentre l&#8217;arrivo di Alberti ne ha regalato uno a coach Di Gioia.<\/p>\n<p>Avvio comunque devastante per i ragazzi di coach Gili, subito pronti al via per un parziale di 9-0 che avrebbe potuto gi\u00e0 segnare la partita non fosse stato per le triple di Biondi (una) ed Alberti (due) che portano alla prima sirena con gli astigiani a dover recuperare un solo possesso (16-14). La seconda decina si ribalta un po&#8217; la situazione con ospiti a chiudere meglio le maglie difensive e si arriva all&#8217;intervallo sul 24-29.<\/p>\n<p>In avvio di ripresa l&#8217;Abc chiude subito il gap e la partita diviene ancor pi\u00f9 equilibrata come testimonia il 41-40 con cui la sirena sancisce la fine del terzo quarto. Abc che prova un break anche in avvio di ultima decina grazie a \u00abCuore\u00bb Masola e Fuso ma il time out richiesto dalla panchina astigiana porta i frutti sperati. Le maglie difensive tornano a serrarsi mentre l&#8217;attacco non si ferma ed all&#8217;ultima sirena il tabellone non lascia dubbi: 54-65 e primi due punti per la Secursat mentre per i carmagnolesi arriva la prima sconfitta stagionale.<\/p>\n<p>(Credit Foto, Scuola Basket Asti)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ASS. BASKET CARMAGNOLA &#8211; SECURSAT SC. BASKET ASTI 54-65<\/strong> <em>(16-14; 24-29; 41-40)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Associazione Basket Carmagnola:<\/strong> Poggio 3, Milone 27, S. Gili ne, Milanesio ne, D. Mammola 2, Giustetto 5, Fuso 4, Masola 4, Porello, A. Gili 9. <strong>Coach:<\/strong> Piero Gili. <strong>Ass.:<\/strong> Riccardo Mammola.<\/p>\n<p><strong>Secursat Scuola Basket Asti:<\/strong>\u00a0Carturan, Gatti 4, Dello Iacovo 6, Smania ne, Alberti 29, Biondi 3, Amico 7, Cotto 2, Zoppi ne, Pavone 14, Forno.\u00a0<strong>Coach:<\/strong> Carlo Di Gioia. <strong>Ass.:<\/strong> Roberto Schinca.<\/p>\n<p><strong>Arbitri:<\/strong> Ferrero Regis e Andreotti.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Serie D &#8211; Girone Top<\/strong><\/p>\n<p><strong>Prima giornata andata:<\/strong> Ab Carmagnola &#8211; Secursat S.B. Asti 54-65; Granda College &#8211; Beinaschese Otb (8\/03); VM Service Gators &#8211; Rolcar Ttb 55-71.<\/p>\n<p><strong>Classifica:<\/strong> Rolcar Torino Teen Basket, Secursat Scuola Basket Asti <em><strong>2<\/strong><\/em>; Granda College*, Beinaschese?, Ab Carmagnola, VM Service Gators <em><strong>0<\/strong><\/em>.<\/p>\n<p><strong>Prossimo turno:<\/strong> Beinaschese Otb &#8211; Ab Carmagnola (4\/03); Rolcar Ttb &#8211; Granda College (6\/03); Secursat S.B. Asti &#8211; SM Service Gators (6\/03).<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":45794,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/45795"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=45795"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/45795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/45794"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=45795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=45795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=45795"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=45795"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=45795"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=45795"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=45795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}