{"id":47999,"date":"2022-07-12T18:40:24","date_gmt":"2022-07-12T16:40:24","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=47999"},"modified":"2022-07-12T18:41:56","modified_gmt":"2022-07-12T16:41:56","slug":"slalom-prorogate-le-iscrizioni-per-il-favale-castello","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2022\/07\/12\/slalom-prorogate-le-iscrizioni-per-il-favale-castello\/","title":{"rendered":"Slalom: prorogate le iscrizioni per il Favale-Castello"},"content":{"rendered":"<p>Ancora qualche ora per iscriversi alla 14^ edizione dello slalom in salita \u201cFavale \u2013 Castello\u201d, in programma sabato 16 e domenica 17 luglio a Favale di Malvaro, nell\u2019entroterra del levante genovese, con l\u2019organizzazione della locale scuderia Sport Favale 07. Le adesioni per partecipare alla gara, valida per il Campionato Italiano di Slalom in salita, di cui \u00e8 la sesta prova, per il Trofeo d\u2019Italia Slalom Nord e per il Trofeo \u201cDanilo Mosca\u201d, sono state infatti prorogate sino alle ore 22 di domani, mercoled\u00ec 13 luglio.<\/p>\n<p>Oltre una cinquantina le iscrizioni fino ad ora pervenute. Massimo riserbo, ovviamente, degli organizzatori sui nomi dei partecipanti: a Favale di Malvaro, per\u00f2, sono attesi tutti i principali protagonisti del \u201ctricolore\u201d 2022 di slalom in salita oltre ai migliori interpreti genovesi, liguri e piemontesi di questa specialit\u00e0. Per tutti i partecipanti, la sera prima della gara, \u00e8 prevista la cena presso gli stand gastronomici della cittadina della Val Fontanabuona, la tradizionale grigliata per trascorrere la vigilia in totale amicizia.<\/p>\n<p>Il tratto di strada interessato dalla competizione sar\u00e0 chiuso al traffico dalle ore 8 alle 18:00. Lo scorso anno, successo del molisano Fabio Emanuele, in lizza con l\u2019Osella PA 9\/90 Alfa Romeo, sui giovani siciliani Michele Puglisi e Emanuele Schillace, entrambi in gara con la Radical SR4 Suzuki.<\/p>\n<p>Info sulla gara sul sito della scuderia, all\u2019indirizzo\u00a0http:\/\/www.sportfavale07.com, oppure su Facebook: Sport Favale 07 Scuderia e Organizzatore.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":6146,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/47999"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=47999"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/47999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/6146"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=47999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=47999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=47999"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=47999"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=47999"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=47999"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=47999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}