{"id":48049,"date":"2022-07-14T09:03:40","date_gmt":"2022-07-14T07:03:40","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=48049"},"modified":"2022-07-14T09:05:53","modified_gmt":"2022-07-14T07:05:53","slug":"tennis-roma-20-alla-grande","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2022\/07\/14\/tennis-roma-20-alla-grande\/","title":{"rendered":"TENNIS &#8211; Roma 20 alla grande"},"content":{"rendered":"<p>Tante news dal \u00abRoma 20\u00bb di Cambiano. Le prime arrivano dal fronte del campionato a squadre D1, dove la compagine del sodalizio nostrano ha ottenuto la promozione alla serie C dopo aver battuto, con un brusco 5-1, i trevigiani del Vedelago Sport. Un\u2019estate da incorniciare quindi per il capitano Alberto Giordano e i suoi atleti Nicola Pereno, Matteo Marniga, Enrico Toscano, Gabriele Ruffinengo e Adriano Maina. Nelle D3 invece prosegue l\u2019avanzata del team guidato da Alessandro Massola e composto da Marco Ugolini, Federico Avataneo, Lupu Nicusor e Marco Aimone che ha sonoramente fermato per 3-0 i torinesi del Circolo Taxi.<\/p>\n<p>Infine il Memorial Franco Mascherpa, open singolare femminile\u00a0 che ha appena terminato di animare i campi del Roma. La vittoria \u00e8 andata alla torinese griffata Sisport Camilla Turini, che in finalissima ha sconfitto per 6-4; 7-6 la sua concittadina\u00a0 del Cus Claudia Franz\u00e8.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":17218,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/48049"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=48049"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/48049\/revisions"}],"predecessor-version":[{"id":48050,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/48049\/revisions\/48050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/17218"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=48049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=48049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=48049"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=48049"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=48049"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=48049"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=48049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}