{"id":4855,"date":"2018-04-13T13:42:23","date_gmt":"2018-04-13T11:42:23","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=4855"},"modified":"2018-04-13T13:42:24","modified_gmt":"2018-04-13T11:42:24","slug":"calendario-scolastico-2018-19","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/04\/13\/calendario-scolastico-2018-19\/","title":{"rendered":"Calendario scolastico 2018-19"},"content":{"rendered":"<p>Suoner\u00e0 luned\u00ec\u00a0<strong>10 settembre<\/strong>\u00a0la prima campanella per gli studenti piemontesi delle scuole di ogni ordine e grado, mentre la data di fine delle lezioni \u00e8 fissata l\u2019<strong>8 giugno<\/strong>\u00a0nelle scuole primarie e secondarie e il\u00a0<strong>30 giugno<\/strong>\u00a0in quelle dell\u2019infanzia. Il\u00a0<strong>calendario scolastico 2018-2019<\/strong>\u00a0\u00e8 stato approvato dalla Giunta regionale del Piemonte, su proposta dall\u2019assessora all\u2019Istruzione Gianna Pentenero, sentito il parere della Conferenza permanente per il Diritto allo studio. Partito il rush finale per la stagione in corso, si mettono quindi le basi per l&#8217;avvio della prossima.<\/p>\n<p align=\"justify\">Il documento garantisce\u00a0206 giorni di lezioneper la scuola primaria e secondariae 224\u00a0per l\u2019infanzia, che si riducono di uno nel caso in cui il Santo Patrono cada in una giornata in cui \u00e8 prevista lezione.<\/p>\n<p align=\"justify\">Le scuole saranno chiuse per le\u00a0<strong>vacanze di Natale<\/strong>\u00a0da luned\u00ec<strong>\u00a024 dicembre 2018 a domenica 6 gennaio 2019,\u00a0<\/strong>mentre sar\u00e0 ponte lungo tra\u00a0<strong>Pasqua e il 25 aprile<\/strong>, con le lezioni sospese da\u00a0<strong>gioved\u00ec 18 a gioved\u00ec 25 aprile 2019<\/strong>. Scuole chiuse anche\u00a0<strong>venerd\u00ec 2 e sabato 3 novembre 2018<\/strong>, in aggiunta alla Festa di Ognissanti, gioved\u00ec 1\u00b0 novembre, e niente lezioni, naturalmente, sabato 8 dicembre Festa dell\u2019Immacolata; mercoled\u00ec 1\u00b0 maggio e il 2 giugno che, tuttavia, cade di domenica.<\/p>\n<p align=\"justify\">Si conferma inoltre per il terzo anno consecutivo la\u00a0<strong>Settimana dello Sport in occasione delle vacanze di Carnevale,\u00a0<\/strong>con le scuole chiuse da\u00a0<strong>sabato 2 a mercoled\u00ec 6 marzo<\/strong>\u00a0e l\u2019invito alle istituzioni scolastiche, nel rispetto della loro autonomia, a concentrare nelle giornate del 7 e 8 marzo\u00a0le attivit\u00e0 formative integrative in materia di sport e benessere.<\/p>\n<p align=\"justify\">\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":3033,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/4855"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=4855"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/4855\/revisions"}],"predecessor-version":[{"id":4856,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/4855\/revisions\/4856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/3033"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=4855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=4855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=4855"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=4855"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=4855"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=4855"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=4855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}