{"id":48562,"date":"2022-08-09T12:56:00","date_gmt":"2022-08-09T10:56:00","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=48562"},"modified":"2024-08-29T07:00:18","modified_gmt":"2023-11-03T07:00:18","slug":"sport-ecco-il-calendario-di-basket-per-lakronos-moncalieri","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2022\/08\/09\/sport-ecco-il-calendario-di-basket-per-lakronos-moncalieri\/","title":{"rendered":"SPORT &#8211; Ecco il calendario di basket per l&#8217;Akronos Moncalieri"},"content":{"rendered":"<p>Pubblicato il calendario della serie A1 femminile di basket che anche quest&#8217;anno vedr\u00e0 Moncalieri tra le protegoniste. Si parte con Geas Sesto San Giovanni, in occasione della prima partita in assoluto della stagione LBF in programma sabato 2 ottobre all\u2019Opening Day di Cagliari.<\/p>\n<p>\u00abE\u2019 un calendario che ci vede subito impegnati con squadre vicine alla nostra \u2018fascia\u2019 \u2013 commenta coach Spanu \u2013 dovremo quindi farci trovare pronti e determinati fin dalla prima partita. Sar\u00e0 molto importante partire col piede giusto, perch\u00e9 \u00e8 un Campionato che non permette disattenzioni e non ci sono mai partite facili\u00bb.<\/p>\n<p>Dopo Geas, l\u2019Akronos affronter\u00e0 in casa l\u2019E-Work Faenza, San Martino di Lupari in trasferta e Basket Crema tra le mura amiche del PalaEinaudi. Poi arriva una sequenza di livello con la trasferta di Sassari, la Virtus Bologna che viene a far visita al PalaEinaudi e la difficilissima partita a domicilio in casa delle Campionesse in carica del Famila Basket Schio.<\/p>\n<p>A met\u00e0 novembre sfida importante in casa con la neopromossa Brixia Brescia, seguita dalla trasferta di Bruschi Galli San Giovanni e Basket Le Mura Lucca.<\/p>\n<p>Ultime sfide del girone, tre squadre di primissima fascia: Reyer Venezia, Magnolia Campobasso e Virtus Eirene Ragusa.<\/p>\n<p>Prima partita in programma al PalaEinaudi: Mercoled\u00ec 5 ottobre vs E-Work Faenza alle 20:30 (seguiranno aggiornamenti su ticketing, abbonamenti ed eventuali variazioni orarie in calendario).<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":46743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/48562"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=48562"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/48562\/revisions"}],"predecessor-version":[{"id":69161,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/48562\/revisions\/69161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/46743"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=48562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=48562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=48562"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=48562"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=48562"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=48562"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=48562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}