{"id":50112,"date":"2022-11-08T14:51:44","date_gmt":"2022-11-08T13:51:44","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=50112"},"modified":"2024-08-29T07:00:01","modified_gmt":"2023-11-03T07:00:01","slug":"rally-due-gi-sport-trionfo-cassino-lomonaco-e-gulmini-si-riconfermano-campioni-italiani","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2022\/11\/08\/rally-due-gi-sport-trionfo-cassino-lomonaco-e-gulmini-si-riconfermano-campioni-italiani\/","title":{"rendered":"RALLY &#8211; Due Gi Sport, trionfo a Cassino: Lomonaco  e Gulmini si riconfermano Campioni Italiani"},"content":{"rendered":"<p>Per il secondo anno consecutivo l&#8217;equipaggio porta colori della scuderia torinese DueGi Sport, si riconferma campione tricolore in classe K10.<br \/>\nUn anno fortunato per Andrea Lomonaco, come al solito navigato da Fabio Gulmini, che si \u00e8 fatto onore dimostrando le sue abilit\u00e0 di pilota anche in condizioni climatiche particolarmente avverse. Al rally del Lazio Cassino Pico, infatti, dopo un anno caratterizzato dalla siccit\u00e0, poco prima della gara si sono abbattute sulle speciali due vere e proprie bombe d&#8217;acqua che hanno costretto i Duegini a prendere una decisione sinora mai considerata.<br \/>\nPer la prima volta, hanno modificato l&#8217;assetto della Citroen C2 in configurazione pioggia e montato le gomme cinturate. Dopo un primo passaggio particolarmente cauto in cui hanno preso le note, si sono resi conto che si potevano fidare della macchina cos\u00ec settata ed hanno spinto sull&#8217;acceleratore. Primi di classe K10, quindicesimi di gruppo e quarantaquattresimi assoluti su oltre centocinquanta partenti: i risultati parlano da soli!<br \/>\nIl pilota ha cos\u00ec commentato la sua ultima gara di questo 2022: &#8220;sono ancora un po&#8217; provato da questa trasferta impegnativa e lontana, ma sono felicissimo. Non poteva andare meglio di cos\u00ec. Abbiamo chiuso questo 2022 nuovamente campioni d&#8217;Italia in classe K10 e ci siamo divertiti! A parte il tempo bizzarro, che ci ha costretti a settare da pioggia la Citroen per la prima volta in assoluto, \u00e8 stata una bellissima esperienza. Siamo andati subito forte, amministrato cos\u00ec gi\u00e0 dal primo tratto cronometrato il vantaggio sul nostro diretto avversario. Fortunatamente la macchina non ci ha dato nessun problema e le prove erano davvero bellissime. Forse da rivedere un pochino la logistica poich\u00e9 i trasferimenti tra le due prove erano di quasi due ore. Una per arrivare in parco chiuso e una per giungere in assistenza. Un rally impegnativo che ha unito tre gare in una. Sabato hanno sospeso due prove, una, il secondo passaggio sulla Viticuso, per via di un incidente di una macchina partita due posizioni prima di noi, che si \u00e8 capottata, mentre l&#8217;ultima prova non ce l&#8217;hanno fatta fare ma non sappiamo la motivazione. Comunque, alla fine tutto \u00e8 bene quel che finisce bene. Adesso ci godiamo qualche giorno di riposo, poi andr\u00f2 a riprendermi la macchina, una bella lavata&#8230;. una copertina sul cofano e&#8230;ci vediamo nel 2023!&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":50111,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/50112"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=50112"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/50112\/revisions"}],"predecessor-version":[{"id":68331,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/50112\/revisions\/68331"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/50111"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=50112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=50112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=50112"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=50112"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=50112"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=50112"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=50112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}