{"id":5084,"date":"2018-04-19T13:16:39","date_gmt":"2018-04-19T11:16:39","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=5084"},"modified":"2018-04-19T13:16:40","modified_gmt":"2018-04-19T11:16:40","slug":"centrale-del-latte-restyling-22-milioni","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/04\/19\/centrale-del-latte-restyling-22-milioni\/","title":{"rendered":"Centrale del Latte, restyling da 22 milioni"},"content":{"rendered":"<p>Un retsyling da 22 milioni di euro per la Centrale del Latte di Torino. Un imponente investimento per rilanciare la societ\u00e0 che far\u00e0 cambiare pelle allo stabilimento torinese, facente parte del Gruppo Centrale del Latte d\u2019Italia, terzo player italiano del mercato del latte. Interventi che avranno una durata di circa 30 mesi che sono stati avviati in questi giorni. In sintesi il progetto prevede la costruzione di un magazzino di stoccaggio dei prodotti finiti interamente automatizzato 4.0, quattro nuove linee di confezionamento, introduzione di due impianti di ultima generazione per il trattamento del latte, ristrutturazione e ampliamento di 1.300 metri quadrati dello stabilimento, ammodernamento di tutti gli impianti per le necessit\u00e0 energetiche dello stabilimento.<\/p>\n<p>&nbsp;<\/p>\n<p>Questi in sintesi gli interventi della durata di circa 30 mesi avviati in questi giorni per il rinnovamento e l\u2019automatizzazione dello stabilimento produttivo di Torino del Gruppo Centrale del Latte d\u2019Italia, societ\u00e0 quotata dal 2001 al segmento STAR di Borsa Italiana oggi terzo player italiano del mercato del latte fresco e a lunga durata, con posizioni di leadership in Piemonte, Liguria, Toscana e Veneto.<\/p>\n<p>Il progetto mira a rispondere alle esigenze di crescita e di innovazione del Gruppo rivolte in particolare all\u2019espansione delle esportazioni, allo sviluppo del canale di vendita online e all\u2019evoluzione dell\u2019azienda verso l\u2019industria 4.0.<\/p>\n<p>Scendendo nel dettaglio degli interventi, il pi\u00f9 importante riguarda la costruzione di nuovo magazzino di stoccaggio completamente automatizzato che si svilupper\u00e0 sul lato nord dell\u2019area della Centrale, con una dimensione di 700 metri quadrati, 2.688 posti pallet e una capacit\u00e0 di stoccaggio di circa 2,1 milioni di litri di prodotto.<\/p>\n<p>Sotto il profilo della produzione, verranno introdotte quattro nuove linee di confezionamento per rispondere a nuove esigenze di prodotti e di formati, e due impianti all\u2019avanguardia per il trattamento del latte. Infine, in un\u2019ottica di efficientamento e risparmio energetico gli impianti frigoriferi e per la produzione di vapore verranno totalmente rinnovati e saranno dotati delle pi\u00f9 moderne tecnologie energy-saver.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":5085,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/5084"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=5084"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/5084\/revisions"}],"predecessor-version":[{"id":5086,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/5084\/revisions\/5086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/5085"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=5084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=5084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=5084"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=5084"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=5084"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=5084"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=5084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}