{"id":51394,"date":"2023-01-29T17:54:56","date_gmt":"2023-01-29T16:54:56","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=51394"},"modified":"2024-08-29T06:59:35","modified_gmt":"2023-11-03T06:59:35","slug":"motori-35-anni-con-la-due-gi-sport","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/01\/29\/motori-35-anni-con-la-due-gi-sport\/","title":{"rendered":"MOTORI &#8211; 35 anni con la Due Gi Sport"},"content":{"rendered":"<p>E difficile capacitarsi del tempo che \u00e8 trascorso da quando la Due Gi Sport Moncalieri muoveva i suoi primi passi nel mondo del motori e si ritagliava un proprio spazio, meritatissimo, nel panorama dei rally. Correva l&#8217;anno 1988 quando Giorgio Gabetti e Marco Giordanino davano vita a questa realt\u00e0 tutta nostrana che oggi, domenica 29 gennaio 2023, ha alzato i calici in onore del trentacinquesimo anniversario della fondazione. Direttivo, soci, amici, simpatizzanti, addetti ai lavori e anche noi de &#8220;il Mercoled\u00ec&#8221;; c\u2019erano proprio tutti a brindare in piena convivialit\u00e0 a questo straordinario compleanno in quel di Traves, nell&#8217;ambito di un incontro che ha unito il piacere della tavola a quello dello stare insieme. Patron della giornata ovviamente il presidente Gabetti, che anche questa volta, nell&#8217;ambito delle tradizionali premiazioni di fine-inizio stagione agonistica, non ha dimenticato nessuno, a partire dalla sua spalla Fabrizio Ponzano, autentica anima del sodalizio e punto di riferimento per driver e navigatori. Ma sul palco sono sfilati anche tanti altri personaggi che hanno fatto e fanno tuttora la storia della Due Gi Sport, che manco a dirlo sar\u00e0 gi\u00e0 in pista il prossimo  fine settimana (4-5 febbraio) in occasione dell&#8217;ouverture della stagione corsaiola, ovvero il Ronde Val Merula di Andora. Tanti i programmi in vista quindi, ma nel frattempo sono stati dati i doverosi onori all&#8217;equipaggio che per il secondo anno consecutivo (il 2022) si \u00e8 accaparrato il titolo tricolore nella classe K10. Parliamo di Andrea Lomonaco e Fabio Gulmini. Tutta per loro l&#8217;\u2019apertura delle premiazioni che hanno intervallato le varie portate di questa domenica di festa e sport. E ora occhi puntanti sul campionato che va ad iniziare, nel quale corso la Due Gi Sport non mancher\u00e0 di dare spettacolo per la gioia dei suoi tanti supporter. Segno di una storia che prosegue imperterrita la sua corsa negli anni, che passano \u00e8 vero, ma sono sempre pi\u00f9 ricchi di soddisfazioni.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":51393,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34,10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/51394"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=51394"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/51394\/revisions"}],"predecessor-version":[{"id":67563,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/51394\/revisions\/67563"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/51393"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=51394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=51394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=51394"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=51394"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=51394"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=51394"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=51394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}