{"id":52177,"date":"2023-03-14T07:01:35","date_gmt":"2023-03-14T06:01:35","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=52177"},"modified":"2024-08-29T03:42:17","modified_gmt":"2023-11-03T03:42:17","slug":"cambiano-parte-il-cineforum-biblioteca","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/03\/14\/cambiano-parte-il-cineforum-biblioteca\/","title":{"rendered":"CAMBIANO &#8211; Parte il cineforum in biblioteca"},"content":{"rendered":"<p>Serata cinema con il Cineforum a Cambiano, in Biblioteca.\u00a0Ingresso gratuito e non basta: snack e bevande offerte dagli organizzatori dell&#8217;Associazione &#8220;Dai&#8221; e la Biblioteca Civica &#8220;F.lli Angelo e Stefano Jacomuzzi&#8221; , con il patrocinio del Comune di Cambiano.\u00a0La prima delle quattro serate: mercoled\u00ec 15 marzo ore 20.45 con il film \u201cSe mi lasci ti cancello\u201d, diretto da Michel Gondry con protagonisti Jim Carrey e Kate Winslet, e Elijah Wood, Mark Ruffalo, Kirsten Dunst, Tom Wilkinson.\u00a0Sceneggiatura vincitrice dell&#8217;Oscar 2005 di Charlie Kaufman<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":3282,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52177"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=52177"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52177\/revisions"}],"predecessor-version":[{"id":67195,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52177\/revisions\/67195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/3282"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=52177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=52177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=52177"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=52177"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=52177"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=52177"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=52177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}