{"id":52339,"date":"2023-03-22T16:00:27","date_gmt":"2023-03-22T15:00:27","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=52339"},"modified":"2024-08-29T03:42:16","modified_gmt":"2023-11-03T03:42:16","slug":"moncalieri-tenta-di-rapinare-un-passate-e-si-nasconde-al-meditur-arrestato","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/03\/22\/moncalieri-tenta-di-rapinare-un-passate-e-si-nasconde-al-meditur-arrestato\/","title":{"rendered":"MONCALIERI &#8211; Tenta di rapinare un passate e si nasconde al Meditur: arrestato"},"content":{"rendered":"<p>I carabinieri hanno arrestato un uomo di origine nigeriana, per aver tentato di rapinare un passante nella zona di via Postiglione, a Moncalieri. Dopo aver bloccato la potenziale vittima ha cercato di malmenarla per accaparrarsi soldi e cellulare. L&#8217;altro ha reagito e il malvivente si \u00e8 dato alla fuga cercando riparo all&#8217;ex Meditur. Nel frattempo i carabinieri sono giunti sul posto e hanno intercettato il rapinatore.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":4609,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52339"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=52339"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52339\/revisions"}],"predecessor-version":[{"id":67055,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52339\/revisions\/67055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/4609"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=52339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=52339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=52339"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=52339"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=52339"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=52339"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=52339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}