{"id":52418,"date":"2023-03-28T07:24:54","date_gmt":"2023-03-28T05:24:54","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=52418"},"modified":"2024-08-29T03:42:16","modified_gmt":"2023-11-03T03:42:16","slug":"carmagnola-aperto-il-parcheggio-di-piazza-italia-interno","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/03\/28\/carmagnola-aperto-il-parcheggio-di-piazza-italia-interno\/","title":{"rendered":"CARMAGNOLA &#8211; Aperto il parcheggio di piazza Italia interno"},"content":{"rendered":"<p>L\u2019area interna di piazza Italia, a Carmagnola, con ingresso da via Gobetti angolo viale Garibaldi viene temporaneamente messa a disposizione per il parcheggio dei veicoli. A comunicarlo il Comune di Carmagnola con una nota resa pubblica nei giorni scorsi. Il posteggio all\u2019interno del foro boario sar\u00e0 infatti autorizzato fino al prossimo 4 aprile\u00a02023, data di smontaggio del\u00a0luna park\u00a0di piazza Bobba e piazza Mazzini.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":4293,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52418"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=52418"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52418\/revisions"}],"predecessor-version":[{"id":67104,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52418\/revisions\/67104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/4293"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=52418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=52418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=52418"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=52418"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=52418"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=52418"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=52418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}