{"id":52983,"date":"2023-04-28T07:02:29","date_gmt":"2023-04-28T05:02:29","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=52983"},"modified":"2024-08-29T03:42:11","modified_gmt":"2023-11-03T03:42:11","slug":"carmagnola-don-iosif-incontra-papa-francesco","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/04\/28\/carmagnola-don-iosif-incontra-papa-francesco\/","title":{"rendered":"CARMAGNOLA &#8211; Don Iosif incontra Papa Francesco"},"content":{"rendered":"<p>Nella giornata di mercoled\u00ec 26 aprile il Parroco di Carmagnola-Salsasio,\u00a0 Don Iosif Patrascan ha partecipato all&#8217;udienza generale di Papa Francesco in piazza San Pietro a Roma in Vaticano. Con lui molti Sacerdoti di origine romena in occasione dei loro anniversari di Sacerdozio. Per don Iosif i primi 10 anni a servizio della Chiesa. Durante l&#8217;incontro con il Santo Padre don Iosif ha portato i saluti dell&#8217;Arcivescovo di Torino Mons. Roberto Repole, ringraziando per averlo scelto come guida della Chiesa torinese e i saluti delle Parrocchie di Salsasio, Casanova e Vallongo. Per don Iosif \u00e8 stato un incontro ricco di emozioni e di gioia. In passato aveva incontrato anche i Papi Benedetto XVI e Giovanni Paolo II.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":52982,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52983"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=52983"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52983\/revisions"}],"predecessor-version":[{"id":66519,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/52983\/revisions\/66519"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/52982"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=52983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=52983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=52983"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=52983"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=52983"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=52983"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=52983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}