{"id":53142,"date":"2023-05-09T14:58:46","date_gmt":"2023-05-09T12:58:46","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=53142"},"modified":"2024-08-29T03:42:11","modified_gmt":"2023-11-03T03:42:11","slug":"carmagnola-il-21-maggio-appuntamento-con-la-stracarmagnola","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/05\/09\/carmagnola-il-21-maggio-appuntamento-con-la-stracarmagnola\/","title":{"rendered":"CARMAGNOLA &#8211; Il 21 maggio appuntamento con la StraCarmagnola"},"content":{"rendered":"<p>Il 21 maggio 2003 appuntamento con la StraCarmagnola, manifestazione sportiva e camminata non agonistica libera a tutti con due distanze previste: 5 e 10 km. Il ricavato della manifestazione sar\u00e0 devoluto all&#8217;ugi, Unione genitori italiani. Le iscrizioni si possono fare presso il centro sportivo Carmasport, da luned\u00ec a venerd\u00ec delle ore 15 alle ore 17, oppure online su www.carmeeventi.com. La gara di 10 km partir\u00e0 alle ore 9:30, mentre quella di 5 km alle ore 11. Quota di partecipazione: 10 euro per ogni adulto, 5 per i minori dai 6 ai 12 anni. Gratis per i bambini fino a 5 anni, ammessi solo per la gara di 5 km.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":5610,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/53142"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=53142"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/53142\/revisions"}],"predecessor-version":[{"id":66638,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/53142\/revisions\/66638"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/5610"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=53142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=53142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=53142"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=53142"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=53142"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=53142"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=53142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}