{"id":53313,"date":"2023-05-18T07:03:19","date_gmt":"2023-05-18T05:03:19","guid":{"rendered":"https:\/\/www-ilmercoledi-news-*.sitenm.com\/?p=53313"},"modified":"2024-08-29T03:42:10","modified_gmt":"2023-11-03T03:42:10","slug":"nichelino-rinviata-la-giornata-sportiva-studentesca-20230518-0503-192547","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/05\/18\/nichelino-rinviata-la-giornata-sportiva-studentesca-20230518-0503-192547\/","title":{"rendered":"NICHELINO &#8211; Rinviata la giornata sportiva studentesca"},"content":{"rendered":"<p>Il fine settimana con le previsioni meteo avverse portano rinvii e spostamenti a diversi eventi organizzati nei giorni scorsi. A Nichelino, la 31esima edizione della \u201cGIORNATA SPORTIVA STUDENTESCA DELLA SOLIDARIET\u00c0\u201d \u00e8 stata rinviata a mercoled\u00ec 24 maggio, sempre dalle 8.30 alle 12.30, presso il Parco Miraflores (Boschetto).<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":49847,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/53313"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=53313"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/53313\/revisions"}],"predecessor-version":[{"id":66494,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/53313\/revisions\/66494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/49847"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=53313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=53313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=53313"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=53313"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=53313"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=53313"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=53313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}