{"id":54586,"date":"2023-07-19T17:35:50","date_gmt":"2023-07-19T15:35:50","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/?p=54586"},"modified":"2024-08-29T03:42:02","modified_gmt":"2023-11-03T03:42:02","slug":"rally-pierfrancesco-verbilli-segno-nel-michelin-trofeo-italia-alladriatico","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/07\/19\/rally-pierfrancesco-verbilli-segno-nel-michelin-trofeo-italia-alladriatico\/","title":{"rendered":"RALLY &#8211; Pierfrancesco Verbilli a segno nel Michelin Trofeo Italia all\u2019Adriatico"},"content":{"rendered":"<p>Continua la galoppata solitaria di Pierfrancesco Verbilli in Quinta Zona, conquistando il bottino pieno di punti del Michelin Trofeo Italia al 30\u00b0 Rally Adriatico di sabato 15 e domenica 16 luglio. Il pilota portacolori di Publisport Racing \u00e8 stato protagonista di una gara perfetta che lo ha portato a conquistare sulla terra urbinate il successo in Classe R3, guidando la classifica dall\u2019inizio alla fine, e la 35esima piazza assoluta con la sua Renault Clio a fianco della navigatrice Sara Montavoci. Classifica \u2013 Il successo di Urbino permette a Verbilli di allungare in classifica di Terzo Raggruppamento, Quinta Zona di Michelin Trofeo Italia, grazie anche alla precedente vittoria di San Marino e alla seconda piazza al Rally Bianco Azzurro. Verbilli ora ha un buon margine di vantaggio su Giorgio Liguori (30,30 punti) vincitore della prima gara stagionale, e assente nelle successive. Il prossimo appuntamento del Michelin Trofeo Italia in Zona-5 sar\u00e0 il 6\u00b0 Rally Salsomaggiore Terme (quarta gara della stagione in zona) in programma il 29-30 luglio a Salsomaggiore Terme (PR).<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":54585,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/54586"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=54586"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/54586\/revisions"}],"predecessor-version":[{"id":65988,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/54586\/revisions\/65988"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/54585"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=54586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=54586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=54586"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=54586"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=54586"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=54586"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=54586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}