{"id":55556,"date":"2023-09-07T13:04:33","date_gmt":"2023-09-07T11:04:33","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=55556"},"modified":"2024-08-29T03:41:53","modified_gmt":"2023-11-03T03:41:53","slug":"vinovo-al-castello-la-cerimonia-di-premiazione-del-concorso-di-poesie","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/09\/07\/vinovo-al-castello-la-cerimonia-di-premiazione-del-concorso-di-poesie\/","title":{"rendered":"VINOVO &#8211; Al Castello la cerimonia di premiazione del concorso di poesie"},"content":{"rendered":"<p>La splendida cornice della Sala degli Affreschi del Castello della Rovere del Comune di Vinovo (TO) ospiter\u00e0 per la terza volta consecutiva, venerd\u00ec 20 ottobre alle 20,30, la cerimonia di premiazione della terza edizione del concorso dedicato alle poesie, filastrocche, e da quest&#8217;anno anche la fotografia, targato Il Chisolino e patrocinato dal Comune di Castagnole Piemonte e Vinovo. Ingresso ad invito.<\/p>\n<p>Tutti i premiati saranno contattati telefonicamente. Gli attestati di partecipazione saranno inviati via mail nei giorni successivi alla premiazione.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":18415,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/55556"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=55556"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/55556\/revisions"}],"predecessor-version":[{"id":65523,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/55556\/revisions\/65523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/18415"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=55556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=55556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=55556"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=55556"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=55556"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=55556"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=55556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}