{"id":56214,"date":"2023-10-09T07:35:56","date_gmt":"2023-10-09T05:35:56","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=56214"},"modified":"2024-08-29T03:41:44","modified_gmt":"2023-11-03T03:41:44","slug":"nichelino-musica-da-vedere-alla-palazzina-di-caccia-20231009-0535-564620","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/10\/09\/nichelino-musica-da-vedere-alla-palazzina-di-caccia-20231009-0535-564620\/","title":{"rendered":"NICHELINO &#8211; Musica da vedere alla palazzina di caccia"},"content":{"rendered":"<p>Domenica 15 ottobre, ore 10.30, alla Palazzina di Caccia c&#8217;\u00e8 &#8220;Musica da Vedere,\u00a0Natura e artificio&#8221;. La visita \u201cmusicale\u201d che fa rivivere gli antichi rituali della caccia reale rappresentati nelle tele del Cignaroli al suono dei corni di Sant\u2019Uberto.<\/p>\n<p>Il paesaggio sonoro rappresentato nelle tele di Vittorio Amedeo Cignaroli\u00a0rivive alla Palazzina di Caccia di Stupinigi attraverso\u00a0l\u2019arte musicale dei suonatori di corno da caccia.<\/p>\n<p>Le musiche che corrispondevano all\u2019antico cerimoniale venatorio della v\u00e8nerie royale (la caccia a cavallo con cani da seguita), vengono riproposte da una sonorizzazione delle opere curata dall\u2019Equipaggio della Regia Venaria, ensemble musicale dell\u2019Accademia di Sant\u2019Uberto, costituita nel 1996 e riconosciuta dall\u2019Unesco\u00a0Patrimonio Immateriale dell\u2019Umanit\u00e0. Lo strumento impiegato \u00e8 la trompe d\u2019Orl\u00e9ans, corno circolare naturale, senza fori, tasti o pistoni, di agevole impiego anche a cavallo, per trasmettere le sequenze dell\u2019azione venatoria nel folto della foresta.<\/p>\n<p>\u201cMusica da Vedere\u201d \u00e8 una visita guidata con sonorizzazione del percorso di visita.<\/p>\n<p>Alle 15.45 \u00e8 in programma invece la visita guidata sulla figura di Carlo Emanuele III per i possessori dell\u2019Abbonamento Musei Torino Piemonte, nell\u2019ambito di AM CLUB (le visite speciali di Abbonamento Musei alle Residenze Reali Sabaude).<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":46889,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56214"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56214"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56214\/revisions"}],"predecessor-version":[{"id":56216,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56214\/revisions\/56216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/46889"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56214"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56214"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56214"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56214"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}