{"id":5626,"date":"2018-05-03T17:25:22","date_gmt":"2018-05-03T15:25:22","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=5626"},"modified":"2018-05-03T17:25:24","modified_gmt":"2018-05-03T15:25:24","slug":"pecetto-baby-calciatori-al-campo-del-busello","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/05\/03\/pecetto-baby-calciatori-al-campo-del-busello\/","title":{"rendered":"Pecetto: baby calciatori al campo del Busello"},"content":{"rendered":"<p>PECETTO \u2013 Domenica 6 maggio, a partire dalle 10.30, il campo sportivo del Busello di Pecetto ospiter\u00e0 la simpatica iniziativa denominata \u201cGiocando con il pallone\u201d, ovvero una giornata che i bambini potranno dedicare, insieme ai genitori, alla scoperta della disciplina calcistica. Il tutto sotto l\u2019occhio esperto dei tecnici della Polisportiva Pecetto nell\u2019ambito delle iniziative BusZeroSei, la rassegna di eventi gratuiti dedicata alle famiglie pecettesi con figli piccoli. L\u2019attivit\u00e0 \u00e8 rivolta alla fascia 3-8 anni 011.860.99.96. In caso di brutto tempo l\u2019iniziativa si svolger\u00e0 in un campo chiuso.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":5627,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/5626"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=5626"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/5626\/revisions"}],"predecessor-version":[{"id":5628,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/5626\/revisions\/5628"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/5627"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=5626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=5626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=5626"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=5626"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=5626"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=5626"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=5626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}