{"id":56280,"date":"2023-10-11T07:10:13","date_gmt":"2023-10-11T05:10:13","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=56280"},"modified":"2024-08-29T03:41:44","modified_gmt":"2023-11-03T03:41:44","slug":"moncalieri-presentata-cruda-belta-stagione-musicale-promossa-da-archeia","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/10\/11\/moncalieri-presentata-cruda-belta-stagione-musicale-promossa-da-archeia\/","title":{"rendered":"MONCALIERI &#8211; Presentata &#8216;Cruda Belt\u00e0&#8217; stagione musicale promossa da Archeia"},"content":{"rendered":"<p align=\"left\">40 musicisti, 10 attori, 3 compositori oltre a uno staff di 15 tecnici, fotografi, fonici e videomaker, tutti under 30: sono i protagonisti di<strong>\u00a0Cruda belt\u00e0<\/strong>, la stagione musicale articolata fra\u00a0<strong>Moncalieri, Torino e Collegno<\/strong>\u00a0e\u00a0<strong>promossa da Archeia<\/strong>, una orchestra di archi formata tutta da giovanissimi. Patrocinata dalla Citt\u00e0 metropolitana di Torino e dalla Citt\u00e0 di Moncalieri, la stagione si compone di 4 spettacoli che fondono musica, canto e teatro, e che si rivolgono anche alle scuole.<\/p>\n<p align=\"left\">Il cartellone di spettacoli musicali, presentato in conferenza stampa da Archeia Orchestra nella sala del 15\u00b0 piano della Citt\u00e0 metropolitana \u00e8 stato realizzato con opere inedite attraverso testi e musiche originali, sul tema del cambiamento climatico e del suo impatto sulle generazioni presenti e future.<\/p>\n<p align=\"left\">\u201c\u00c8 con grande soddisfazione che oggi do il benvenuto nella sede della Citt\u00e0 metropolitana ai protagonisti della stagione musicale di Archeia \u2013 commenta\u00a0<strong>Valentina Cera,<\/strong>\u00a0consigliera delegata metropolitana con delega alle politiche giovanili \u2013 Perch\u00e9 \u00e8 bellissimo vedere un gruppo di giovani prendere l\u2019iniziativa per farsi strada in un settore difficile com\u2019\u00e8 quello musicale e cercare di restituire al territorio, attraverso le loro competenze e la creazione di una stagione anche rivolta alle scuole, il suo patrimonio culturale. Spesso quando si parla di politiche giovanili si affrontano le problematiche dei soggetti pi\u00f9 svantaggiati, come i Neet, e invece in quest\u2019occasione vediamo l\u2019altra faccia della medaglia, quella di giovani che percorrono una strada in salita con energia e impegno. \u201d<\/p>\n<p align=\"left\">\n<p align=\"left\">Laura Pompeo, assessore alla cultura di Moncalieri \u2013 che ospita lo spettacolo inaugurale alle Fonderie Limone il 19 novembre \u2013 ha ricordato che Archeia Orchestra torna a Moncalieri per la terza volta ed \u00e8 ormai conosciuta e apprezzatissima dal pubblico.<\/p>\n<p align=\"left\">\n<p align=\"left\">Archeia Orchestra nasce a Torino nel 2017\u00a0nella forma di un ensemble di strumentisti ad arco.\u00a0Nel 2019 si costituisce l\u2019Associazione\u00a0ononima, organizzazione interamente coordinata da giovani under 30 che attraverso l\u2019orchestra realizza e produce spettacoli collaborando con compositori emergenti e creando reti con le realt\u00e0 artistiche giovanili del territorio.<\/p>\n<p align=\"left\">\n<p align=\"left\">Ciascun evento della stagione mette in rete i\u00a0giovani\u00a0musicisti\u00a0di Archeia Orchestra e giovani artisti professionisti con l\u2019obiettivo di alimentare l\u2019economia del settore culturale e favorire l\u2019aumento di posizioni professionali per giovani studenti neolaureati nel mondo dello spettacolo, il tutto in un\u2019ottica di interdisciplinariet\u00e0.<\/p>\n<p align=\"left\">\n<p align=\"left\">Negli spettacoli sono coinvolti attori del collettivo Tecnologia Filosofica, della compagnia Gatto Vaccino Teatro. Presenti in qualit\u00e0 di ospiti speciali il musicista e regista Marco Amistadi, l\u2019attrice e doppiatrice Roberta Maraini, lo scrittore e direttore creativo Enrico Granzotto, i compositori Giuliano Comoglio e Filippo Don\u00e0, la cantante soprano Francesca Lo Verso, il fisico e matematico Daniele Cane.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":56275,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56280"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56280"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56280\/revisions"}],"predecessor-version":[{"id":56283,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56280\/revisions\/56283"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/56275"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56280"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56280"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56280"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56280"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}