{"id":56422,"date":"2023-10-17T14:33:15","date_gmt":"2023-10-17T12:33:15","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=56422"},"modified":"2024-08-29T03:41:43","modified_gmt":"2023-11-03T03:41:43","slug":"poirino-maxi-porcilaia-ternavasso-le-osservazioni-dei-comitati-che-si-oppongono","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/10\/17\/poirino-maxi-porcilaia-ternavasso-le-osservazioni-dei-comitati-che-si-oppongono\/","title":{"rendered":"POIRINO &#8211; Maxi porcilaia a Ternavasso, le osservazioni dei comitati che si oppongono"},"content":{"rendered":"<p>I comitati che si oppongono al progetto della maxi porcilaia su Poirino, in zona Ternavasso al confine con Carmagnola, hanno presentato nei giorni scorsi in Citt\u00e0 Metropolitana le osservazioni al progetto. &#8220;Nelle Osservazioni &#8211; spiegano i comitato Pro Natura e Pro Ternavasso -, viene precisato che l\u2019area oggetto di intervento \u00e8 soggetta a vincoli di inedificabilit\u00e0 per ragioni di difesa idrogeologica ed ambientale dei luoghi e degli insediamenti: il progetto viola i limiti per l\u2019edificazione e non rispetta la distanza dal rio Venesima, presumibilmente per trarre vantaggio dal corso d\u2019acqua.<\/p>\n<p>Si evidenzia quanto sia irragionevole che venga autorizzato un impianto che produce reflui che conserva per mesi in cisterne da quasi 40 metri di diametro, a poche decine di metri da un rio che, in caso anche involontario, sarebbe il primo recettore dei liquami che si riverserebbero, inquinando un&#8217;area enormemente estesa e sottoposta a specifico vincolo paesaggistico.<\/p>\n<p>L&#8217;area dell&#8217;impianto risulta localizzata in stretta adiacenza al sito Natura 2000 \u201cPeschiere e Laghi di Pralormo\u201d, localizzata in Comune di Ceresole d&#8217;Alba che prevede il divieto di edificazione e costruzione di nuove infrastrutture in un intorno di 500 metri dagli stagni esistenti.<\/p>\n<p>Il Piano Paesaggistico Regionale in vigore definisce l&#8217;area oggetto del progetto, per la presenza di flora, fauna e acque soggette a particolare tutela, come zona di particolare pregio e ad elevato interesse agronomico e di rilevanza paesaggistica. Questo per la presenza del borgo di Ternavasso, dal Castello e dal Lago di Ternavasso, protetti dalla Soprintendenza delle Belle Arti come beni da valorizzare e da salvaguardare. \u00c8 evidente che l\u2019installazione di un allevamento suinicolo intensivo delle dimensioni in progetto (8.400 capi dichiarati), si pone in contrasto ed appare inconciliabile con gli obiettivi espressamente individuati dal PPR.<\/p>\n<p>L\u2019edificazione dell\u2019allevamento avrebbe, per dimensioni e immissioni, un impatto negativo irreversibile, sulla fruibilit\u00e0 dei beni paesaggistici e culturali che sorgono nelle vicinanze e sulla intera zona e la sua fruibilit\u00e0 naturalistica.<\/p>\n<p>Nel progetto manca la valutazione delle emissioni del particolato e del calcolo degli inquinanti che inevitabilmente lo stabilimento per la natura e dimensioni dell\u2019allevamento intensivo, produrrebbe ed immetterebbe nell\u2019ambiente.<\/p>\n<p>Peraltro, dall\u2019analisi del progetto risulta che la quantit\u00e0 massima di suini insediabile \u00e8 maggiore di 10.000 capi, maggiore rispetto ai conteggi effettuati dal proponente su 8.400 capi, con un conseguente ulteriore incremento della produzione di inquinante.<\/p>\n<p>Il Proponente non dichiara la piena propriet\u00e0 della strada d&#8217;accesso all\u2019allevamento, n\u00e9 tantomeno allega il titolo di acquisto o l&#8217;eventuale autorizzazione del terzo soggetto proprietario favorevole all&#8217;allargamento dell\u2019incrocio che condurrebbe allo stabilimento, allargamento che risulterebbe in ogni caso insufficiente per la svolta di mezzi pesanti senza che questi invadano la corsia opposta. Il calcolo dell\u2019impatto odorifero \u00e8 stato effettuato sulla base della erronea classificazione di alcune attivit\u00e0 sensibili presenti in zona: la Cascina Cavallino \u00e8 sede di una casa di cura per persone con disabilit\u00e0 e il Poggio Agrisport svolge attivit\u00e0 di scuola privata (tennis e centro estivo) e attivit\u00e0 con scuole dell\u2019infanzia, scuole primarie e secondarie&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":56420,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56422"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56422"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56422\/revisions"}],"predecessor-version":[{"id":56423,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56422\/revisions\/56423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/56420"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56422"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56422"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56422"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56422"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}