{"id":56432,"date":"2023-10-17T14:43:55","date_gmt":"2023-10-17T12:43:55","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=56432"},"modified":"2024-08-29T03:41:43","modified_gmt":"2023-11-03T03:41:43","slug":"moncalieri-il-volto-moderno-della-medicina-e-la-salute-delle-famiglie-biblioteca","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/10\/17\/moncalieri-il-volto-moderno-della-medicina-e-la-salute-delle-famiglie-biblioteca\/","title":{"rendered":"MONCALIERI &#8211; Il volto moderno della Medicina e la Salute delle famiglie in biblioteca"},"content":{"rendered":"<p>Cosa hanno in comune la\u00a0medicina di\u00a0famiglia, il\u00a0servizio\u00a0sanitario\u00a0nazionale e la\u00a0medicina\u00a0moderna? Un obiettivo: mantenere la salute delle persone. Questi tre temi vengono affrontati nel suo ultimo libro da Claudio Tosi.\u00a0Il volto moderno della Medicina e la Salute delle Famiglie,\u00a0pagina per pagina, riesce a mantenere lo sguardo rivolto alle innovazioni pratiche e ai concetti teorici che costituiranno la cosiddetta\u00a0medicina del futuro. Un manuale prezioso che l\u2019autore presenta a Moncalieri luned\u00ec 23 ottobre (ore 17,30, biblioteca Arduino in via Cavour 31), in dialogo con l\u2019assessore alla Cultura Laura Pompeo. Nato dalla passione di un medico di famiglia, questo manuale di salute rende apparentemente semplici argomenti complessi grazie al proprio stile divulgativo caratterizzato da chiarezza\u00a0e schematicit\u00e0,\u00a0riuscendo non solo a rispondere a ogni domanda del lettore in merito alle strutture pi\u00f9 profonde della nostra\u00a0sanit\u00e0 e alle cure adottate, ma anche evidenziando per quale motivo sia pi\u00f9 importante la prevenzione di ogni altra cosa. Ingresso libero fino ad esaurimento posti e diretta facebook.<\/p>\n<p>\u201cIl\u00a0messaggio di fondo del libro\u00a0\u00e8\u00a0questo: l\u2019unico modo per mantenere la nostra salute \u00e8 compiere scelte responsabili e ragionate sullo stile di vita\u00a0&#8211;<b>\u00a0<\/b><b>sintetizza<\/b><b>\u00a0l\u2019assessore alla Cultura Laura Pompeo<\/b><b>\u00a0\u2013\u00a0<\/b>L\u2019incontro con Tosi\u00a0sar\u00e0 ricco di stimoli a questo riguardo: affidandoci al nostro medico non saremo mai pi\u00f9 in pensiero per la nostra longevit\u00e0\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":6949,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56432"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56432"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56432\/revisions"}],"predecessor-version":[{"id":56436,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56432\/revisions\/56436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/6949"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56432"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56432"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56432"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56432"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}