{"id":56560,"date":"2023-10-24T07:26:22","date_gmt":"2023-10-24T05:26:22","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=56560"},"modified":"2024-08-29T03:41:42","modified_gmt":"2023-11-03T03:41:42","slug":"carmagnola-uninstallazione-contro-la-violenza-sulle-donne-croce-rossa","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/10\/24\/carmagnola-uninstallazione-contro-la-violenza-sulle-donne-croce-rossa\/","title":{"rendered":"CARMAGNOLA &#8211; Un&#8217;installazione contro la violenza sulle donne in Croce Rossa"},"content":{"rendered":"<p>Da qualche giorno, sulla facciata della sede della Croce Rossa (lato parcheggio Piazza Primo Maggio), \u00e8 stata collocata una nuova installazione contro la violenza sulle donne, realizzata dal gruppo Donne in citt\u00e0 Carmagnola. &#8220;Noi volontari come il Gruppo donne in citt\u00e0 &#8211; spiegano &#8211; riteniamo che l&#8217;attenzione su questa problematica rimanga sempre alta, perch\u00e9 solo con un enorme cambiamento culturale e sociale, potremo vedere un capovolgimento della situazione. Insieme alle rose \u00e8 stato ricamato il 1522, numero di emergenza nazionale da chiamare per chiedere aiuto in caso di violenza&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":56559,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56560"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56560"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56560\/revisions"}],"predecessor-version":[{"id":65291,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56560\/revisions\/65291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/56559"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56560"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56560"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56560"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56560"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}