{"id":56595,"date":"2023-10-25T07:22:08","date_gmt":"2023-10-25T05:22:08","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/?p=56595"},"modified":"2024-08-29T03:41:42","modified_gmt":"2023-11-03T03:41:42","slug":"carignano-nuovi-lavori-per-limitare-le-infiltrazioni-nel-duomo","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/10\/25\/carignano-nuovi-lavori-per-limitare-le-infiltrazioni-nel-duomo\/","title":{"rendered":"CARIGNANO &#8211; Nuovi lavori per limitare le infiltrazioni nel Duomo"},"content":{"rendered":"<p>Partono cantieri di restauro al Duomo di Carignano, per eliminare le infiltrazioni d\u2019acqua e recuperare il baldacchino ligneo e gli affreschi del Gaidano. IL cantiere coster\u00e0 circa 17mila euro, che si aggiungo ai 60mila gi\u00e0 spesi per il restauro delle volte delle Cappelle laterali e dell\u2019altare affidati al Consorzio San Luca. I lavori si rendono necessari per nuove infiltrazioni d&#8217;acqua.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":56594,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56595"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56595"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56595\/revisions"}],"predecessor-version":[{"id":65322,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56595\/revisions\/65322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/56594"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56595"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56595"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56595"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56595"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}