{"id":56599,"date":"2023-10-25T14:56:07","date_gmt":"2023-10-25T12:56:07","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/?p=56599"},"modified":"2024-08-29T03:41:41","modified_gmt":"2023-11-03T03:41:41","slug":"candiolo-presentato-il-bilancio-sociale-dellistituto-di-ricerca","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/10\/25\/candiolo-presentato-il-bilancio-sociale-dellistituto-di-ricerca\/","title":{"rendered":"CANDIOLO &#8211; Presentato il bilancio sociale dell&#8217;istituto di ricerca"},"content":{"rendered":"<p>Nel 2022 la Fondazione Piemontese per la Ricerca sul Cancro ha investito oltre 26 milioni di euro per le attivit\u00e0 di cura e ricerca sul cancro dell\u2019Istituto di Candiolo &#8211; IRCCS, grazie a 47 mila donazioni e a oltre 262 mila firme del 5X1000. Prosegue lo sviluppo dell\u2019Istituto insieme al continuo ammodernamento del parco tecnologico, per curare sempre pi\u00f9 persone e farlo sempre meglio. Allegra Agnelli: \u201cVogliamo tenere fede alla nostra missione: contribuire alla sconfitta del cancro. Il nostro impegno non si ferma e non rallenta mai, perch\u00e9 il futuro \u00e8 oggi\u201d.<\/p>\n<p>Candiolo, 25 ottobre 2023 \u2013 Oltre un milione e trecentocinquantamila prestazioni ambulatoriali erogate dall\u2019Istituto di Candiolo \u2013 IRCCS, 275 ricercatori impegnati nei 39 laboratori di ricerca; un Impact Factor crescente; oltre 500 operatori coinvolti nelle attivit\u00e0 di assistenza. Come ogni anno questi sono solo alcuni dei traguardi, riassunti nel Bilancio Sociale e di Sostenibilit\u00e0 della Fondazione Piemontese per la Ricerca sul Cancro dati 2022, che \u00e8 stato presentato agli stakeholder con un evento digitale.<\/p>\n<p>Un \u201cviaggio\u201d fatto di immagini e interviste, ma anche di emozioni, condotto dal Direttore de La Repubblica, Maurizio Molinari, che ha intervistato alcuni dei protagonisti: Allegra Agnelli Presidente della Fondazione Piemontese per la Ricerca sul Cancro, la Professoressa Anna Sapino, Direttore Scientifico dell\u2019Istituto di Candiolo &#8211; IRCCS, la Professoressa Caterina Marchi\u00f2, Responsabile della Diagnostica Molecolare e dell\u2019Attivit\u00e0 di Ricerca dell\u2019Anatomia Patologica, Annamaria Gull\u00e0, cervello di rientro che ha trovato nel nuovo laboratorio di Ematologia Traslazionale e Immunologia di Candiolo il luogo ideale dove sviluppare i propri progetti, dopo una carriera negli Stati Uniti. A seguire, Gianmarco Sala, Direttore della Fondazione Piemontese per la Ricerca sul Cancro, ha evidenziato gli importanti investimenti fatti grazie alla generosit\u00e0 delle persone, che hanno permesso di dotare l\u2019Istituto, tra le tante cose, di una nuova Tomoterapia (la seconda \u00e8 in arrivo nei prossimi mesi), di un Laboratorio di Oncoematologia, di un nuovo reparto di Cardio Oncologia, dell\u2019Hospice Monviso e di cominciare a progettare la nuova Biobanca. E per finire Fabiana Multari, mamma e paziente che ha aperto la Milano Fashion Week per testimoniare quanto la prevenzione e la ricerca siano state fondamentali nel suo percorso.<\/p>\n<p>\u201cIl Bilancio Sociale per noi \u00e8 un appuntamento fondamentale &#8211; ha sottolineato Allegra Agnelli &#8211; perch\u00e9 vogliamo rappresentare non solo numeri, ma soprattutto il legame di fiducia creato con tutti coloro che ci supportano: imprese, istituzioni, donatori. \u00c8 la nostra determinazione che ci guida dal 1986, il nostro impegno non si ferma e non rallenta mai, perch\u00e9 il futuro \u00e8 oggi\u201d. \u201cIl 2022 &#8211; ha aggiunto Allegra Agnelli &#8211; \u00e8 stato per noi un anno di risultati veramente importanti. Grazie alla raccolta fondi diretta e ai contributi del 5X1000 abbiamo potuto sostenere numerosi progetti di ricerca riguardanti tutte le patologie tumorali, portati avanti ogni giorno nei 39 laboratori dell\u2019Istituto di Candiolo &#8211; IRCCS dai circa 275 ricercatori, italiani e internazionali, che ne costituiscono il patrimonio umano e scientifico. La generosit\u00e0 dei nostri sostenitori, oltre 33 mila persone solo nell\u2019ultimo anno, ci ha consentito, inoltre, di destinare importanti risorse per mantenere l\u2019eccellenza dell\u2019Istituto di Candiolo &#8211; IRCCS nelle strumentazioni all\u2019avanguardia, di cui \u00e8 un esempio la nuova Tomoterapia di ultima generazione che ha dato un ulteriore contributo al rinnovamento del parco tecnologico dell\u2019Istituto. Si tratta di un sistema innovativo per il trattamento delle patologie neoplastiche tra i pi\u00f9 avanzati a livello mondiale\u201d.<\/p>\n<p>\u201cVogliamo tenere fede alla nostra missione &#8211; ha concluso il Presidente &#8211; vogliamo trovare nuove cure per il cancro attraverso la ricerca, progettando ulteriori studi, piani e strategie, e mettendo a sistema conoscenze e competenze per raggiungere terapie sempre pi\u00f9 personalizzate e migliori risultati in termini di qualit\u00e0 di vita e di guarigione. Senza mai perdere di vista l\u2019attenzione e il rispetto per la persona\u201d.<\/p>\n<p>Il Direttore della Fondazione, Gianmarco Sala, ha messo inoltre in rilievo lo straordinario legame che c\u2019\u00e8 da oltre da 37 anni tra la Fondazione e i suoi sostenitori: \u201cLo dimostrano i\u00a0dati\u00a0della raccolta fondi provenienti dal 5X1000, dalla raccolta diretta, dalle eredit\u00e0 e legati e dagli eventi. Nel 2022 abbiamo ricevuto oltre 47 mila donazioni che hanno permesso alla Fondazione di destinare oltre 26 milioni di euro alle attivit\u00e0 di cura e ricerca sul cancro dell\u2019Istituto di Candiolo \u2013 IRCCS. Siamo pronti a mettere a disposizione nuovi laboratori per i nostri ricercatori e nuovi macchinari per le attivit\u00e0 cliniche: a novembre entrer\u00e0 in azione il nuovo reparto di Cardio Oncologia\u201d.<\/p>\n<p>Sul piano di sviluppo avviato nel maggio 2021, \u201cCantiere Candiolo\u201d, Sala ha precisato: \u201cA breve saranno completati OncoLab, che ospiter\u00e0 nuovi laboratori per la messa a punto di innovative soluzioni farmacologiche, e Recycle Lab, per lo stoccaggio e differenziazione dei rifiuti ospedalieri. Sono in fase di progettazione le opere del prossimo lotto di lavori: la nuova Biobanca di circa 2.500 mq, che raccoglier\u00e0 e conserver\u00e0 i tessuti biologici in un\u2019ottica di future terapie oncologiche, e Cyberknife che permette efficienza e efficacia nelle attivit\u00e0 di cura\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Significativi in particolare gli ultimi dati del\u00a05X1000 relativi alle dichiarazioni dei redditi 2022: 262.770 firme per un importo che ha superato i 12 milioni di euro. \u00c8 una forma di sostegno decisiva e fondamentale per garantire continuit\u00e0 al lavoro dei ricercatori: un impegno che ha permesso di pubblicare oltre 300 lavori sulle pi\u00f9 autorevoli riviste internazionali, con una crescita costante sia dell\u2019Impact Factor (l\u2019indice che misura il numero medio di citazioni ricevute in un anno) sia del numero di citazioni ricevute dai lavori pubblicati dai ricercatori dell\u2019Istituto. Numeri importanti anche per l\u2019assistenza clinica: 510 gli operatori, 1.350.517 le prestazioni ambulatoriali, 8.473 i pazienti ricoverati e 194 protocolli e studi sperimentali attivi.<\/p>\n<p>\u00c8 entrato da poco in funzione anche il nuovo Laboratorio di Ematologia Traslazionale e Immunologia, guidato dalla Dottoressa Annamaria Gull\u00e0, un \u201ccervello di ritorno\u201d che dal prestigioso Dana-Farber\u00a0Cancer Institute di Boston \u00e8 rientrata in Italia, a Candiolo, per portare avanti un\u2019importante ricerca sul mieloma multiplo.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":21868,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56599"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56599"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56599\/revisions"}],"predecessor-version":[{"id":65233,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56599\/revisions\/65233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/21868"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56599"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56599"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56599"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56599"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}