{"id":56625,"date":"2023-10-26T17:09:10","date_gmt":"2023-10-26T15:09:10","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=56625"},"modified":"2024-08-29T03:41:37","modified_gmt":"2023-11-03T03:41:37","slug":"santena-lavori-sulla-pubblica-illuminazione","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/10\/26\/santena-lavori-sulla-pubblica-illuminazione\/","title":{"rendered":"SANTENA &#8211; Lavori sulla pubblica illuminazione"},"content":{"rendered":"<p>Proseguono i lavori di miglioria dell\u2019illuminazione pubblica a Santena. Il Comune ha recentemente emesso una determinazione che mette in moto importanti lavori volti a migliorare l&#8217;illuminazione pubblica nella citt\u00e0. La decisione \u00e8 stata presa in seguito alle segnalazioni dei cittadini residenti, che hanno lamentato la carenza di illuminazione in alcune zone del centro cittadino, in particolare in via Campini e in via Magellano, oltre alla necessit\u00e0 di sostituire alcuni punti luce obsoleti o danneggiati in diverse aree.<\/p>\n<p>\u00abCome Amministrazione ci stiamo impegnando per rendere i servizi pubblici efficienti, tra cui l&#8217;illuminazione pubblica, per il benessere e la sicurezza dei cittadini\u00a0&#8211; motiva\u00a0Paolo Romano vicesindaco e assessore ai Lavori pubblici &#8211;\u00a0Dopo un&#8217;attenta valutazione del territorio da parte del servizio tecnico comunale, \u00e8 emersa la necessit\u00e0 di uniformare l&#8217;illuminazione in alcune strade, dove la presenza sporadica di punti luce o addirittura l&#8217;assenza di illuminazione creano problemi di visibilit\u00e0 notturna e potenziali rischi per la sicurezza\u00bb.<\/p>\n<p>Gli interventi previsti includono:<\/p>\n<p>* In via Magellano, la fornitura e l&#8217;installazione di 3 nuovi corpi illuminanti (punti luce) su plinti gi\u00e0 predisposti per estendere l&#8217;illuminazione pubblica comunale.<\/p>\n<p>* In via Campini, la fornitura e l&#8217;installazione di 7 nuovi corpi illuminanti (punti luce) e la preparazione di quanto necessario per una nuova illuminazione pubblica.<\/p>\n<p>* Il ripristino di un punto luce incidentato in strada Vecchia di Chieri.<\/p>\n<p>* Il ripristino di un punto luce incidentato in via Avataneo, vicino al civico n. 45.<\/p>\n<p>* Ripristino attraversamento pedonale illuminato in via Asti<\/p>\n<p>\u00abIl Comune ha ritenuto questi interventi urgenti, poich\u00e9 la situazione attuale comporta rischi per i cittadini e gli utenti delle strade interessate-\u00a0prosegue Romano\u00a0&#8211; I lavori saranno affidati direttamente a ENEL SOLE S.R.L.\u00bb<\/p>\n<p>L&#8217;importo totale degli interventi ammonta a 35.000 euro: \u00abCome Comune abbiamo anche previsto la possibilit\u00e0 di impegnare ulteriori fondi per lavori futuri che potrebbero rendersi necessari, garantendo cos\u00ec una costante manutenzione dell&#8217;illuminazione pubblica per la sicurezza e il benessere della comunit\u00e0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":56624,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56625"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56625"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56625\/revisions"}],"predecessor-version":[{"id":65206,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56625\/revisions\/65206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/56624"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56625"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56625"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56625"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56625"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}