{"id":56681,"date":"2023-10-31T06:55:48","date_gmt":"2023-10-31T05:55:48","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/?p=56681"},"modified":"2024-08-29T03:41:36","modified_gmt":"2023-11-03T03:41:36","slug":"pecetto-apre-il-nuovo-asilo-nido-paese","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/10\/31\/pecetto-apre-il-nuovo-asilo-nido-paese\/","title":{"rendered":"PECETTO &#8211; Apre il nuovo asilo nido in paese"},"content":{"rendered":"<p>A Pecetto apre il nuovo nido. Il 6 Novembre 2023 la Scuola dell\u2019Infanzia Santa Maria della Neve aprir\u00e0 le porte anche ai pi\u00f9 piccoli. Inizier\u00e0 un nuovo servizio rivolto ai bambini dai 12 ai 36 mesi. Le iscrizioni per il micronido sono gi\u00e0 aperte. Per informazioni telefonare al numero 011 8609194 oppure mandare una mail a info@asilopecetto.it. Per chi volesse conoscere le educatrici e la struttura sono in programma due Open day nei giorni 14 Dicembre (dalle 18.00 alle 19.30) e 13 Gennaio (dalle 10.00 alle 12.00).<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":53405,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56681"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56681"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56681\/revisions"}],"predecessor-version":[{"id":56682,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56681\/revisions\/56682"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/53405"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56681"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56681"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56681"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56681"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}