{"id":56782,"date":"2023-11-06T07:07:53","date_gmt":"2023-11-06T06:07:53","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=56782"},"modified":"2024-08-29T03:41:36","modified_gmt":"2023-11-03T03:41:36","slug":"cambiano-caro-bollette-se-ne-discute-biblioteca","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/11\/06\/cambiano-caro-bollette-se-ne-discute-biblioteca\/","title":{"rendered":"CAMBIANO &#8211; Caro bollette? Se ne discute in biblioteca"},"content":{"rendered":"<p>Il Comune di Cambiano e l&#8217;Associazione Consumatori Chierese invitano a partecipare alla serata informativa dal titolo &#8220;Aumenti nelle fatture di gas e luce &#8211; procedura per la corretta tutela&#8221;. L&#8217;appuntamento \u00e8 per gioved\u00ec 9 novembre ore 21.00 presso la Biblioteca Civica &#8220;F.lli Angelo e Stefano Jacomuzzi&#8221;. Sar\u00e0 possibile portare le proprie fatture di gas e luce per consentirne l&#8217;analisi nel corso della serata.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":3282,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56782"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56782"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56782\/revisions"}],"predecessor-version":[{"id":65193,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56782\/revisions\/65193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/3282"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56782"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56782"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56782"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56782"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}