{"id":56874,"date":"2023-11-08T14:35:08","date_gmt":"2023-11-08T13:35:08","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/?p=56874"},"modified":"2024-08-29T03:41:35","modified_gmt":"2023-11-03T03:41:35","slug":"carmagnola-nuovi-fondi-per-lanalisi-genetica-canina","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/11\/08\/carmagnola-nuovi-fondi-per-lanalisi-genetica-canina\/","title":{"rendered":"CARMAGNOLA &#8211; Nuovi fondi per l&#8217;analisi genetica canina"},"content":{"rendered":"<p>Nuova convenzione tra Comune di Carmagnola con l\u2019Istituto Zooprofilattico Sperimentale del Piemonte legata all&#8217;analisi genetica canina, per combattere l&#8217;abbandono delle deiezioni. A seguito dell\u2019esaurimento dei tamponi previsti, a luglio era stato approvato un nuovo accordo con l\u2019Istituto che prevedeva l&#8217;implementazione, la tenuta della Banca di dati genetici dei cani e l&#8217;esecuzione di nuove a analisi genetiche. Circa 18 mila euro per un periodo con scadenza giugno 2024. La determina \u00e8 stata firmata pochi giorni fa.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":1164,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56874"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56874"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56874\/revisions"}],"predecessor-version":[{"id":56875,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56874\/revisions\/56875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/1164"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56874"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56874"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56874"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56874"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}