{"id":56883,"date":"2023-11-09T07:02:35","date_gmt":"2023-11-09T06:02:35","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=56883"},"modified":"2024-08-29T03:41:35","modified_gmt":"2023-11-03T03:41:35","slug":"santena-un-incontro-pubblico-per-la-conoscenza-e-la-gestione-delle-emozioni","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/11\/09\/santena-un-incontro-pubblico-per-la-conoscenza-e-la-gestione-delle-emozioni\/","title":{"rendered":"SANTENA &#8211; Un incontro pubblico per la conoscenza e la gestione delle emozioni"},"content":{"rendered":"<p>Sabato 11 novembre dalle 10 alle 12 si terr\u00e0 a Santena un incontro informativo gratuito aperto a tutta la cittadinanza. Il titolo \u00e8 &#8220;Conoscere e Gestire le Emozioni: mettersi in contatto con il cuore per promuovere un benessere globale&#8221;<\/p>\n<p>Si parler\u00e0 di:<\/p>\n<p>\u2022 Come le emozioni influiscono nella nostra vita quotidiana?<\/p>\n<p>\u2022 Sviluppare intelligenza emotiva per migliorare le nostre relazioni<\/p>\n<p>\u2022 E se le emozioni prendono il controllo? Riconoscere stress e ansia<\/p>\n<p>\u2022 Raggiungere un maggior benessere emotivo attraverso la mindfulness<\/p>\n<p>Appuntamento in Sala Consiliare presso il Palazzo Comunale Via Cavour 39, Santena.<\/p>\n<p>L&#8217;evento \u00e8 a cura dell&#8217;Associazione OltreAps Carignano e della Dott.ssa Beatrice Gaboardi<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":22440,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56883"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=56883"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56883\/revisions"}],"predecessor-version":[{"id":65095,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/56883\/revisions\/65095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/22440"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=56883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=56883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=56883"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=56883"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=56883"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=56883"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=56883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}