{"id":57044,"date":"2023-11-16T06:51:19","date_gmt":"2023-11-16T05:51:19","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/?p=57044"},"modified":"2024-08-29T03:41:34","modified_gmt":"2023-11-03T03:41:34","slug":"vinovo-arrivo-la-nuova-ambulanza-veterinaria-per-lippodromo","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2023\/11\/16\/vinovo-arrivo-la-nuova-ambulanza-veterinaria-per-lippodromo\/","title":{"rendered":"VINOVO &#8211; In arrivo la nuova ambulanza veterinaria per l&#8217;ippodromo"},"content":{"rendered":"<p>Sar\u00e0 consegnata sabato 18 novembre in occasione del G.P. ANACT la nuova ambulanza veterinaria che sar\u00e0 operativa presso l\u2019Ippodromo di Vinovo e il suo centro di allenamento, grazie alla collaborazione con l\u2019Associazione ANIMAL RESCUE TEAM, nata nel 2007 per iniziativa di un gruppo di Medici Veterinari ed amici amanti degli animali. Fin dalla sua creazione, la Onlus opera al fine di promuovere e tutelare l\u2019etico rapporto uomo-animale-ambiente.<\/p>\n<p>Il servizio prevede la messa a disposizione dell\u2019ambulanza cavalli tipologia Trailer attrezzato, autorizzato in termini di legge ed idoneo al soccorso e al trasporto di cavalli incidentati e\/o feriti, dentro e fuori l\u2019ippodromo verso clinica veterinaria o verso le scuderie.<\/p>\n<p>L\u2019ambulanza \u00e8 autonoma nei suoi meccanismi costruttivi e pu\u00f2 essere trainata da un autoveicolo dotato di gancio di traino o da trattore.<\/p>\n<p>L\u2019ambulanza cavalli viene messa a disposizione sotto la diretta supervisione della Direzione Sanitaria del dottore veterinario Matteo Galliani, in collaborazione con il medico veterinario di servizio ed al servizio del personale tecnico prescelto, che sar\u00e0 adeguatamente formato in materia di funzionamento e manutenzione.<\/p>\n<p>Nei periodi extra corse l\u2019ambulanza rimane a disposizione del centro per servizi di soccorso \/ trasporto urgente \/ rescue horse in collaborazione con un medico veterinario referente del posto.<\/p>\n<p>\u201cUn investimento importante e necessario- racconta Silvano Ferraris Direttore dell\u2019impianto torinese- molto spesso l\u2019immediatezza nell\u2019intervenire su di un infortunio con le giuste attrezzature, pu\u00f2 salvare la vita ad un animale. Avere a disposizione sul posto un\u2019ambulanza \u00e8 un grande passo avanti, al quale abbiamo aderito volentieri. Ovviamente non tutti possono utilizzarla, ma solo Veterinari autorizzati dall\u2019Usl.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":57042,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/57044"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=57044"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/57044\/revisions"}],"predecessor-version":[{"id":65034,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/57044\/revisions\/65034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/57042"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=57044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=57044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=57044"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=57044"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=57044"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=57044"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=57044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}