{"id":5846,"date":"2018-05-09T18:51:45","date_gmt":"2018-05-09T16:51:45","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=5846"},"modified":"2018-05-09T18:51:47","modified_gmt":"2018-05-09T16:51:47","slug":"ricco-carnet-camminate-collina","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/05\/09\/ricco-carnet-camminate-collina\/","title":{"rendered":"Ricco carnet di camminate in collina"},"content":{"rendered":"<p>MONCALIERI &#8211; Camminatori della collina fatevi avanti, perch\u00e9 le proposte per i due fine settima in arrivo sono davvero tante. \u00a0<strong>Sabato 12 maggio \u2013 Tra Collina e Po &#8211; Camminata con i bastoncini proposta da Walking Center Piemonte. <\/strong>Panoramica camminata di un\u2019intera giornata con un Istruttore\/Guida Escursionistica Ambientale, in un tratto dell\u2019Anello Verde che si svolge sulla collina e lungo il Po. Itinerario: Reaglie \u2013 Parco Ottolenghi &#8211; Pian Gambino \u2013 Basilica di Superga \u2013 Valle di Costa Parigi \u2013 Parco del Meisino \u2013 Madonna del Pilone. Sviluppo tot. Km 17- dislivello m +350 \/ -450.<\/p>\n<p>Pranzo al sacco a Superga con propri viveri o presso risto-bar. Ritrovo ore 9.30 fermata bus linea 30, Piazzale Marco Aurelio\/ V. Boccaccio (capolinea bus C.so San Maurizio dopo V. Bava). Contributo di partecipazione: 5 \u20ac, munirsi di biglietto per bus urbano. Gratuit\u00e0 fino ad anni 12. L\u2019uscita verr\u00e0 effettuata con un numero minimo di cinque partecipanti ed annullata in caso di pioggia. Info e iscrizioni entro ore 13 venerd\u00ec 11\/05\/18, 3924258175 info@walkingcenterpiemonte.it, www.walkingcenterpiemonte.it. <strong>Domenica 13 maggio, \u201cCamminata sul sentiero della calce\u201d<\/strong> Gli \u201cAmici dell\u2019Ambiente di Baldissero\u201d organizzano una camminata alla scoperta delle testimonianze della lavorazione della \u201cpietra da calce\u201d, materiale che ha consentito la costruzione dei pi\u00f9 importanti monumenti della Torino barocca tra cui la Basilica di Superga. Ritrovo alle ore 8.30 sul il piazzale della Basilica di Superga ai piedi della gradinata centrale, verranno percorsi i sentieri 59 fino a Rivodora, poi Strada Viale, Strada Moncanino, i sentieri 66 e 65. Si soster\u00e0 al Centro Polivalente di Rivodora per il pranzo al sacco. Lunghezza totale circa 8 chilometri, dislivello totale 750 metri. La partecipazione \u00e8 gratuita, per informazioni Nicola 348 2902784, Carlo 3477923429. <strong>Domenica 13 maggio \u2013 Miglio a Miglio<\/strong> Vista l&#8217;adesione dell&#8217;Istituto Comprensivo di Gassino al progetto Ministeriale \u201cUn miglio al giorno\u201d il Coordinamento sentieri di Gassino- Associazione Turistica Pro Loco Gassino &#8211; Associazione scout Corpo Nazionale Giovani Esploratori\/ici Sezione di Gassino sostengono l&#8217;iniziativa con questa passeggiata da Gassino a San Raffaele Cimena \u2013 Azienda Pochettino. Ritrovo a Gassino piazzetta di fronte alla Farmacia Tarnavasio ore 9.00. Percorso nella piana tra Gassino T.se e San Raffaele Cimena. Visita alla Azienda Pochettino e Club Amici del Cavallo. Circa 7 km andata e ritorno. Pranzo al sacco. Contattare per informazioni: 3296734631 (Coordinamento Sentieri di Gassino) \u2013 3355963217 (Associazione Turistica Pro Loco Gassino) \u2013 3331670085 (Associazione Scout Corpo Nazionale Giovani Esploratori\/ici Sezione di Gassino). <strong>Domenica 13 maggio 2018 \u2013 Tra borgate, vigne e boschi della collina attorno San Genesio<\/strong> Facile escursione di mezza giornata. Da San Genesio percorso ad anello tra vigne, boschi e borgate. Disl. 300 mt, Diff. E. Ritrovo Piazza Ceriana di San Genesio ore 9, al termine dell&#8217;escursione possibilit\u00e0 di consumare pranzo campagnolo sul padiglione della festa patronale organizzata dalla Societ\u00e0 Cattolica Agricolo-Operaia (per prenotazioni: Silvio 3498092209, Gian Maria 3316040886. <strong>Domenica 20 maggio: Camminata sui sentieri di Montaldo T.se, <\/strong>organizzata dal Gruppo Alpini Montaldese Percorso ad anello con partenza alle 8.30 dal Circolo Polisportivo Montaldese. Sono previsti punti di ristoro lungo il percorso. Quota di partecipazione 4 \u20ac. Info: Giordano 3289716948, Angelo e-mail<\/p>\n<p>bertone.ancilo@libero.it. <strong>Domenica 20 maggio \u2013 34\u00b0 edizione Camminata revigliaschese<\/strong> Ritrovo in Piazza Sagna a Revigliasco (Moncalieri) dalle ore 8.30. La partenza \u00e8 prevista verso le ore 10. Questo evento prevede una passeggiata lungo un facile e suggestivo percorso collinare dove saranno presenti numerosi punti di ristoro. Facili giochi a premi intratterranno i partecipanti alla passeggiata. Ai primi 400 iscritti paganti sar\u00e0 offerta una maglietta omaggio. All&#8217;arrivo \u00e8 previsto un goloso spuntino unito a vino e bevande ed estrazione di premi. Quota di iscrizione 9 \u20ac per adulti e bambini di et\u00e0 superiore ai 10 anni; gratuito ad ogni bambino fino a 10 anni accompagnato da un adulto (sono ammessi animali solo se al guinzaglio) Per eventuali comunicazioni preghiamo contattare la segreteria di Pro Loco Revigliasco al numero 0118131220<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":2242,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/5846"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=5846"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/5846\/revisions"}],"predecessor-version":[{"id":5847,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/5846\/revisions\/5847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/2242"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=5846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=5846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=5846"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=5846"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=5846"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=5846"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=5846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}