{"id":58644,"date":"2024-02-01T18:52:39","date_gmt":"2024-02-01T17:52:39","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/?p=58644"},"modified":"2024-08-29T03:41:20","modified_gmt":"2023-11-03T03:41:20","slug":"basket-serie-a2-sara-alle-16-la-palla-due-tra-tecnoengineering-e-stella-azzurra","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2024\/02\/01\/basket-serie-a2-sara-alle-16-la-palla-due-tra-tecnoengineering-e-stella-azzurra\/","title":{"rendered":"Basket serie A2, sar\u00e0 alle 16 la palla a due tra Tecnoengineering e Stella Azzurra"},"content":{"rendered":"<p>Sar\u00e0 alle 16 e non alle 20,30 come da calendario la palla a due tra Tecnoengineering Libertas Moncalieri e Stella Azzurra Roma. L&#8217;incontro, valido per la quarta giornata di ritorno (la 17a del campionato per i pi\u00f9 scaramantici) sar\u00e0 a tutti gli effetti uno dei big match della settimana pur riguardando la parte bassa della classifica. Per il quintetto moncalierese, autoretrocessosi e rinnovatosi quasi completamente al termine la passata stagione, potrebbe infatti trattarsi dell&#8217;ultima occasione per agganciare e superare le capitoline che le precedono di 2 punti in classifica lasciando cos\u00ec a loro la scomodissima sedia del fanalino di coda, ossia quello che al termine della regular season decreter\u00e0 la retrocessione diretta in serie B.<\/p>\n<p>Come di consueto l&#8217;ingresso sar\u00e0 gratuito pertanto ci si attende gli spali stracolmi per spingere le \u00ablunette\u00bb, che potrebbero ritrovare la verve di Elisa Pasero da alcune settimane ai box, al successo atteso ormai da un girone completo (l&#8217;unica vittoria lo scorso anno sempre al PalaEinaudi, con le Foxes Giussano affrontate sabato scorso).<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":58643,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/58644"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=58644"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/58644\/revisions"}],"predecessor-version":[{"id":64460,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/58644\/revisions\/64460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/58643"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=58644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=58644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=58644"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=58644"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=58644"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=58644"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=58644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}