{"id":61217,"date":"2024-06-20T07:18:32","date_gmt":"2024-06-20T05:18:32","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/?p=61217"},"modified":"2024-08-29T03:40:48","modified_gmt":"2023-11-03T03:40:48","slug":"trofarello-domenica-23-giugno-si-scende-campo-per-ricordare-gino-guglielmo","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2024\/06\/20\/trofarello-domenica-23-giugno-si-scende-campo-per-ricordare-gino-guglielmo\/","title":{"rendered":"TROFARELLO &#8211; Domenica 23 giugno si scende in campo per ricordare Gino Guglielmo"},"content":{"rendered":"<p>Domenica 23 giugno si scende in campo per ricordare Gino Guglielmo, conosciutissimo a Trofarello anche per l\u2019attivit\u00e0 nel settore calcistico.<\/p>\n<p>Ed \u00e8 su questo terreno che tanti amici lo ricorderanno insieme ai figli nel primo Memorial Gino Guglielmo, che vede il patrocinio del Comune. Appuntamento al campo comunale dell\u2019Asd Trofarello (in via Torricelli) con una dodici ore non stop di calcio a 5, a cu prenderanno parte 8 squadre, \u201cper ricordare &#8211; dicono gli organizzatori &#8211; un amico di Trofarello con la passione, con il cuore e con il sorriso\u201d.<\/p>\n<p>Ingresso libero.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":55152,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/61217"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=61217"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/61217\/revisions"}],"predecessor-version":[{"id":61221,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/61217\/revisions\/61221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/55152"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=61217"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=61217"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=61217"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=61217"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=61217"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=61217"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=61217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}