{"id":61498,"date":"2024-07-04T14:35:51","date_gmt":"2024-07-04T12:35:51","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/?p=61498"},"modified":"2024-08-29T03:40:46","modified_gmt":"2023-11-03T03:40:46","slug":"moncalieri-si-distrae-un-attimo-e-gli-rubano-parte-dellincasso-della-sala-giochi","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2024\/07\/04\/moncalieri-si-distrae-un-attimo-e-gli-rubano-parte-dellincasso-della-sala-giochi\/","title":{"rendered":"MONCALIERI &#8211; Si distrae un attimo e gli rubano parte dell&#8217;incasso della sala giochi"},"content":{"rendered":"<p>Furto in una sala giochi di\u00a0 Corso Trieste, a Moncalieri. Il responsabile del locale ha riferito ai Carabinieri che gli autori del furto erano persone presenti nel locale al momento del fatto, ma non \u00e8 stato in grado di identificarli.<\/p>\n<p>Secondo la sua testimonianza, stava raccogliendo i soldi dalle macchinette per depositarli nella cassaforte. Dopo averli appoggiati per un istante, si \u00e8 girato e, quando si \u00e8 voltato di nuovo, i soldi erano spariti. L&#8217;incasso parziale, che ammontava a circa 1.800 euro, \u00e8 stato sottratto con destrezza dagli ignoti.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":2175,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/61498"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=61498"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/61498\/revisions"}],"predecessor-version":[{"id":63149,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/61498\/revisions\/63149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/2175"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=61498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=61498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=61498"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=61498"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=61498"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=61498"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=61498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}