{"id":6342,"date":"2018-05-24T14:12:08","date_gmt":"2018-05-24T12:12:08","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=6342"},"modified":"2018-05-24T14:12:09","modified_gmt":"2018-05-24T12:12:09","slug":"trofarello-spaccata-allagenzia-scommesse-match-point","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/05\/24\/trofarello-spaccata-allagenzia-scommesse-match-point\/","title":{"rendered":"TROFARELLO &#8211; Spaccata all&#8217;agenzia di scommesse Match Point"},"content":{"rendered":"<p>Nuova spaccata alle agenzie di scommesse della zona sud. Dopo il caso di Vinovo la scorsa settimana, ieri notte ad essere colpita \u00e8 stata l&#8217;agenzia Match Point di Trofarello e tra l&#8217;altro non \u00e8 la prima volta che finisce nel mirino dei malviventi. Secondo le ricostruzioni, ignoti hanno sfondato la vetrina per tentare di rubare i soldi che erano all&#8217;interno. Ancora da quantificare l&#8217;ammontare del bottino, le indagini sono portate avanti dai carabinieri.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":6343,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6342"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=6342"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6342\/revisions"}],"predecessor-version":[{"id":6344,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6342\/revisions\/6344"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/6343"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=6342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=6342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=6342"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=6342"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=6342"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=6342"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=6342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}