{"id":6359,"date":"2018-05-25T08:12:46","date_gmt":"2018-05-25T06:12:46","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=6359"},"modified":"2018-05-25T08:12:48","modified_gmt":"2018-05-25T06:12:48","slug":"nichelino-anche-stupinigi-nelle-tappe-della-maratona-reale","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/05\/25\/nichelino-anche-stupinigi-nelle-tappe-della-maratona-reale\/","title":{"rendered":"NICHELINO &#8211; Anche Stupinigi nelle tappe della maratona reale"},"content":{"rendered":"<p>Mettere insieme sport e cultura per far conoscere alle varie tipologie di pubblico le residenze sabaude piemontesi \u00e8 l&#8217;idea di base da cui \u00e8 partita la\u00a0<strong>Maratona Reale<\/strong>, al via domenica 27 maggio con la prima di\u00a0<strong>quattro tappe che si snoderanno fra le regge dei Savoia<\/strong>\u00a0sommando alla fine i 42,195 chilometri di una maratona tradizionale.<\/p>\n<p>Il percorso \u00e8 stato\u00a0<strong>frazionato per renderlo accessibile anche ai concorrenti meno esperti<\/strong>, in modo da coinvolgere pi\u00f9 persone possibile. Palazzo Madama \u00e8 il fulcro della tappa del 27 maggio, che parte nei pressi dei Giardini Reali di Torino, tocca Palazzo Carignano, Castello del Valentino, Cavallerizza Reale e Villa della Regina, per concludersi in Piazzetta Reale. Le successive tappe saranno il 24 giugno intorno al Castello di Racconigi, il 9 settembre alla Palazzina di Caccia di Stupinigi, e il 14 ottobre fra la Reggia di Venaria e il Castello della Mandria.<\/p>\n<p>La Maratona Reale, organizzata da Base Running, prevede\u00a0<strong>un unico pettorale con chip incorporato per tutte le gare<\/strong>, con premiazione alla fine dell&#8217;intero percorso. Ma sar\u00e0 possibile anche partecipare a una sola tappa, senza rientrare nella classifica finale. Ci sar\u00e0 una mini-maratona per i bambini sabato 26 maggio, alla vigilia del via ufficiale.<\/p>\n<p>L&#8217;assessora regionale alla Cultura e al Turismo ha sottolineato durante la conferenza stampa di presentazione il lavoro in corso da anni da parte della Regione per far dialogare tutte le residenze sabaude che hanno propriet\u00e0 differenti, per costruire una promozione comune. Fino a due anni fa infatti non esisteva neppure un pacchetto turistico con il nome di Residenze reali, ma molto si pu\u00f2 ancora fare e questa iniziativa, ha rimarcato l\u2019assessora, \u00e8 un esempio da seguire, perch\u00e9 ha il merito di chiamare in causa lo sport, in Piemonte fondamentale per la promozione turistica.<\/p>\n<p>Secondo le statistiche, ogni quattro partecipanti alle maratone di Base Running, uno proviene da fuori Piemonte e da parte di tutti gli organizzatori si \u00e8 auspicato il coinvolgimento futuro delle altre residenze.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":542,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6359"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=6359"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6359\/revisions"}],"predecessor-version":[{"id":6360,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6359\/revisions\/6360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/542"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=6359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=6359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=6359"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=6359"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=6359"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=6359"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=6359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}