{"id":6497,"date":"2018-05-29T16:02:11","date_gmt":"2018-05-29T14:02:11","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=6497"},"modified":"2018-05-29T16:02:13","modified_gmt":"2018-05-29T14:02:13","slug":"nichelino-festa-primavera-comune-ci-riprova","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/05\/29\/nichelino-festa-primavera-comune-ci-riprova\/","title":{"rendered":"NICHELINO &#8211; Festa di Primavera: il Comune ci riprova"},"content":{"rendered":"<p>Domenica 3 giugno in via XXV Aprile, a Nichelino, si festeggia la primavera con lo sport. La strada sar\u00e0 chiusa al traffico nell&#8217;orario compreso tra le 7 e le 22 e nel tratto compreso tra gli incroci con via Torricelli e con via Torino. Nello stesso tratto stradale \u00e8 prevista l&#8217;apertura straordinaria dei negozi in orario 9 &#8211; 20. Lungo la strada ci saranno esibizioni sportive e di danza. Inoltre esposizioni artigianali e hobbistiche. In pi\u00f9: intrattenimenti con acrobati e artisti circensi di teatrazione e giocoleria. Le esibizioni sportive e danzanti sono a cura di SSd Akuadro Sport, ASD Lineainmovimento, A. D. Pallacanestro Nichelino, Futura sport e Circolo 1\u00b0 Maggio. La festa era stata cancellata qualche settimana fa per il maltempo.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":839,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6497"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=6497"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6497\/revisions"}],"predecessor-version":[{"id":6498,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6497\/revisions\/6498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/839"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=6497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=6497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=6497"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=6497"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=6497"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=6497"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=6497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}