{"id":6581,"date":"2018-05-31T20:03:25","date_gmt":"2018-05-31T18:03:25","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=6581"},"modified":"2018-05-31T20:03:27","modified_gmt":"2018-05-31T18:03:27","slug":"nichelino-grande-successo-liniziativa-ugualmente-diversi","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/05\/31\/nichelino-grande-successo-liniziativa-ugualmente-diversi\/","title":{"rendered":"NICHELINO &#8211; Grande successo per l&#8217;iniziativa: &#8220;Ugualmente diversi&#8221;"},"content":{"rendered":"<p>Grande risposta oggi, 31 maggio, in piazza Dalla Chiesa, per l&#8217;iniziativa \u201cUgualmente diversi\u201d, curata dall&#8217;assessorato all&#8217;Istruzione, dalla ludoteca comunale \u201cLa bottega dei sogni\u201d, dallo spazio bimbi \u201cAranciolimonemandarino!\u201d e dal Consiglio Comunale dei Ragazzi (CCR). Circa un migliaio di bambini &#8211; durante l&#8217;arco della giornata e fino alle 18 &#8211; hanno partecipato all&#8217;appuntamento perdendosi fra le varie installazioni: \u201cPuzzle s-culture\u201d, \u201c1024 &#8211; Puzzle di colori\u201d, \u201cParole in circol-azione\u201d. A fine mattinata un flash mob con gigantesche lettere dell&#8217;alfabeto a rappresentazione del pensiero libero dei bambini. Il presidente del Consiglio Comunale, Franco Ripani, accompagnato dal vicesindaco, Filippo D&#8217;Aveni, e dagli assessori Diego Sarno e Sara Sibona, ha portato i saluti e i ringraziamenti dell&#8217;Amministrazione Comunale.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":6582,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[34],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6581"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=6581"}],"version-history":[{"count":1,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6581\/revisions"}],"predecessor-version":[{"id":6583,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6581\/revisions\/6583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/6582"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=6581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=6581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=6581"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=6581"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=6581"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=6581"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=6581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}