{"id":6616,"date":"2018-06-02T08:31:23","date_gmt":"2018-06-02T06:31:23","guid":{"rendered":"http:\/\/euwps02.tecnavia.com\/ilmercoledi\/news\/?p=6616"},"modified":"2018-06-02T08:31:26","modified_gmt":"2018-06-02T06:31:26","slug":"carmagnola-grande-golf-domenica-girasoli","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2018\/06\/02\/carmagnola-grande-golf-domenica-girasoli\/","title":{"rendered":"Carmagnola grande golf domenica a I Girasoli"},"content":{"rendered":"<p><img alt=\"Carmagnola grande golf domenica a I Girasoli\" title=\"Carmagnola grande golf domenica a I Girasoli\" loading=\"lazy\" class=\"size-full wp-image-6617\" src=\"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-content\/uploads\/sites\/3\/2018\/06\/campo-golf-I-Girasoli.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/wp-content\/uploads\/sites\/3\/2018\/06\/campo-golf-I-Girasoli.jpg 300w, https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/wp-content\/uploads\/sites\/3\/2018\/06\/campo-golf-I-Girasoli-150x150.jpg 150w, https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/wp-content\/uploads\/sites\/3\/2018\/06\/campo-golf-I-Girasoli-32x32.jpg 32w, https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/wp-content\/uploads\/sites\/3\/2018\/06\/campo-golf-I-Girasoli-50x50.jpg 50w, https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/wp-content\/uploads\/sites\/3\/2018\/06\/campo-golf-I-Girasoli-64x64.jpg 64w, https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/wp-content\/uploads\/sites\/3\/2018\/06\/campo-golf-I-Girasoli-96x96.jpg 96w, https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/wp-content\/uploads\/sites\/3\/2018\/06\/campo-golf-I-Girasoli-128x128.jpg 128w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Domenica 3 giugno fa tappa a Carmganola la gara del circuito golfistico Mondovicino Outlet Cup 2018 Golf For Good, manifestazione di sport e solidariet\u00e0 organizzata da Mondovicino Outlet Village.\u00a0L&#8217; edizione 2018 ha nell&#8217;ingresso nel circuito del Golf Club I Girasoli di Carmagnola (Torino), una delle pi\u00f9 significative novit\u00e0.<\/p>\n<p>Il circuito \u00e8 aperto a golfisti dilettanti nazionali e internazionali tesserati presso le rispettive federazioni. La formula di gara \u00e8 di 18 buche stableford individuale su tre categorie.<\/p>\n<p>Il tour si articola in 12 gare di selezione nei Golf Club pi\u00f9 prestigiosi di Piemonte e Liguria. I vincitori delle singole tappe si sfideranno nella Finale del Tartufo Bianco d&#8217;Alba, il 12 settembre, al Golf Club di Cherasco.\u00a0I Golf Club partecipanti &#8211; Cherasco, Royal Park I Roveri, Feudo di Asti, Torino, Margara, I Girasoli, Garlenda, La Margherita, Le Fronde, Rapallo, Degli Ulivi, Boves &#8211; devolveranno il ricavato della manifestazione a sostegno di \u201cConFido: quattro zampe in corsia\u201d, il primo progetto di Pet-Therapy, in grado di dare benefici fisici e psicologici ai malati affetti da SLA e malattie neuromuscolari. Progetto ideato da Mondovicino Outlet Village e realizzato in collaborazione con la Fondazione Vialli e Mauro Onlus, e il Centro Clinico NeMo (NeuroMuscolarOmnicentre) di Arenzano (Genova). I premi delle gare di selezione, non cumulabili, verranno assegnati a: 1\u00b0 lordo (riservato ai giocatori di 1\u00aa Categoria); 1\u00b0 netto di 1\u00aa, 2\u00aa e 3\u00aa Categoria; 2\u00b0 netto di 1\u00aa, 2\u00aa e 3\u00aa Categoria; 3\u00b0 netto di 1\u00aa, 2\u00aa e 3\u00aa Categoria; 1\u00aa Lady; 1\u00b0 Senior; Nearest to the Pin Uomini e Nearest to the Pin Donne.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6616"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=6616"}],"version-history":[{"count":2,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6616\/revisions"}],"predecessor-version":[{"id":6619,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/6616\/revisions\/6619"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=6616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=6616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=6616"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=6616"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=6616"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=6616"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=6616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}