{"id":72088,"date":"2025-01-23T21:00:18","date_gmt":"2025-01-23T20:00:18","guid":{"rendered":"https:\/\/euwps05.newsmemory.com\/ilmercoledi\/news\/?p=72088"},"modified":"2025-01-23T21:01:39","modified_gmt":"2025-01-23T20:01:39","slug":"moncalieri-lavori-di-ripristini-stradali-barauda","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/01\/23\/moncalieri-lavori-di-ripristini-stradali-barauda\/","title":{"rendered":"MONCALIERI &#8211; Lavori di ripristini stradali a Barauda"},"content":{"rendered":"<p align=\"JUSTIFY\">Partono i ripristini definitivi delle strade su scavi gi\u00e0 eseguiti dell\u2019 infrastruttura interrata FTTH a Moncalieri in Str. Barauda, Piazza S. Antonio, V.lo del Forno, Str. Baraudina, Str. Freylia Mezzi. Lavori che servono a rimettere a posto l&#8217;asfalto dopo gli interventi della fibra. Dal giorno 22.01.2025 al giorno 07.02.2025 dalle ore 09.00 alle ore 17.30 partiranno i cantieri che limiteranno la sosta nelle vie sopra indicate e la velocit\u00e0 di transito.<\/p>\n<p align=\"JUSTIFY\">\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":8381,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72088"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=72088"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/8381"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=72088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=72088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=72088"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=72088"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=72088"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=72088"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=72088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}