{"id":72138,"date":"2025-01-27T06:28:29","date_gmt":"2025-01-27T05:28:29","guid":{"rendered":"https:\/\/euwps06.newsmemory.com\/ilmercoledi\/news\/?p=72138"},"modified":"2025-01-27T06:28:31","modified_gmt":"2024-08-30T06:28:31","slug":"nichelino-si-suicido-carcere-dopo-aver-ucciso-moglie-e-figlio-ministero-denunciato-come-responsabile","status":"publish","type":"post","link":"https:\/\/www.ilmercoledi.news\/2025\/01\/27\/nichelino-si-suicido-carcere-dopo-aver-ucciso-moglie-e-figlio-ministero-denunciato-come-responsabile\/","title":{"rendered":"NICHELINO &#8211; Si suicid\u00f2 in carcere dopo aver ucciso moglie e figlio, ministero denunciato come responsabile"},"content":{"rendered":"<p>Alexandro Vito Riccio, nichelinese, il 26 settembre 2021\u00a0 si era suicidato nel carcere di Ivrea, pochi mesi dopo aver ucciso a Carmagnola la compagna ed il figlio piccolo. Il suo suicidio ha sollevato interrogativi sulla gestione dei detenuti in condizioni di vulnerabilit\u00e0 psicologica. Aveva mostrato chiari segnali di disagio mentale, come accertato dalla sostituta procuratrice Valentina Bossi. Il ministero della Giustizia \u00e8 stato citato come responsabile civile, mentre otto persone, tra cui dirigenti, psicologi e psichiatri del penitenziario, sono sotto inchiesta per presunta negligenza.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":43083,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"news-destination":[],"news-source":[],"is_homepage":[581],"ta_other":[],"_links":{"self":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72138"}],"collection":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/comments?post=72138"}],"version-history":[{"count":0,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/posts\/72138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media\/43083"}],"wp:attachment":[{"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/media?parent=72138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/categories?post=72138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/tags?post=72138"},{"taxonomy":"news-destination","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-destination?post=72138"},{"taxonomy":"news-source","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/news-source?post=72138"},{"taxonomy":"is_homepage","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/is_homepage?post=72138"},{"taxonomy":"ta_other","embeddable":true,"href":"https:\/\/www.ilmercoledi.news\/ilmercoledi\/news\/wp-json\/wp\/v2\/ta_other?post=72138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}